{"id":768,"date":"2011-11-12T19:00:22","date_gmt":"2011-11-13T00:00:22","guid":{"rendered":"http:\/\/proposmontreal.com\/?p=768"},"modified":"2016-01-01T15:40:59","modified_gmt":"2016-01-01T20:40:59","slug":"dossier-le-pont-tunnel-hippolyte-lafontaine","status":"publish","type":"post","link":"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/","title":{"rendered":"Dossier: Le Pont-tunnel Hippolyte-Lafontaine"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture approximatif de<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p>L&rsquo;id\u00e9e du Tunnel sous le Saint-Laurent ne date pas d&rsquo;hier, le journal illustr\u00e9 <a href=\"http:\/\/collections.banq.qc.ca\/ark:\/52327\/68026#\" target=\"_blank\">L&rsquo;opinion Publique<\/a> publiait les 22 avril 1880 et 29 juillet 1880 des images d&rsquo;un tunnel ferroviaire qui rejoindrait le Village d&rsquo;Hochelaga \u00e0 Longueuil sur la rive sud. Il aura donc fallu attendre jusqu&rsquo;au 11 mars 1967, soit, 87 ans plus tard pour que l&rsquo;ing\u00e9nierie rejoigne le r\u00eave de plusieurs \u00e0 l&rsquo;\u00e9poque.<\/p>\n<div align=\"center\">\n<figure id=\"attachment_771\" aria-describedby=\"caption-attachment-771\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_avril1880.jpg\"><img decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_avril1880.jpg\" alt=\"\" title=\"Opinion Publique Avril 1880\" width=\"550\" class=\"size-full wp-image-771\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_avril1880.jpg 800w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_avril1880-150x57.jpg 150w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_avril1880-300x115.jpg 300w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption id=\"caption-attachment-771\" class=\"wp-caption-text\">L&#039;Opinion Publique, Avril 1880<\/figcaption><\/figure><br \/>\n<figure id=\"attachment_772\" aria-describedby=\"caption-attachment-772\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_juillet1880.jpg\"><img decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_juillet1880.jpg\" alt=\"Opinion Publique Avril 1880\" title=\"Opinion Publique Juillet 1880\" width=\"550\"  class=\"size-full wp-image-772\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_juillet1880.jpg 800w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_juillet1880-150x120.jpg 150w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_juillet1880-300x240.jpg 300w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><figcaption id=\"caption-attachment-772\" class=\"wp-caption-text\">L&#039;Opinion Publique, Juillet 1880<\/figcaption><\/figure>\n<\/div>\n<p>Le Pont-Tunnel Louis-Hippolyte-Lafontaine est un lien en deux parties, soit le tunnel entre Montr\u00e9al et l&rsquo;\u00eele Charron de 1.5 kilom\u00e8tres et d&rsquo;un pont reliant l&rsquo;\u00eele Charron \u00e0 la Rive-Sud de 457 m\u00e8tres. Le Pont-Tunnel est aussi un lien important de l&rsquo;autoroute Trans-Canadienne, une autoroute F\u00e9d\u00e9rale-Provincialle reliant les dix provinces du Canada et faisant plus ou moins 8 000 kilom\u00e8tres. Lors du trac\u00e9 de celle-ci, le quartier de Mercier dans l&rsquo;Est de l&rsquo;\u00eele de Montr\u00e9al est choisi pour accueillir l&rsquo;axe routier, les plans furent accepter en 1962 et la construction en 1963.<\/p>\n<div align=\"center\">\n<figure id=\"attachment_770\" aria-describedby=\"caption-attachment-770\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/mercier1960.jpg\" alt=\"Quartier de Mercier\" title=\"Quartier de Mercier\" width=\"550\" height=\"461\" class=\"size-full wp-image-770\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/mercier1960.jpg 550w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/mercier1960-150x125.jpg 150w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/mercier1960-300x251.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><figcaption id=\"caption-attachment-770\" class=\"wp-caption-text\">Quartier de Mercier quelques ann\u00e9es avant l&#039;expropriation<\/figcaption><\/figure>\n<\/div>\n<p>Tout comme lors de la construction du Pont Jacques-Cartier, l&rsquo;autoroute 25 en direction du Pont-Tunnel fit d\u00e9placer plusieurs personnes et cr\u00e9a une cicatrice dans le quartier de la Paroisse St-Fran\u00e7ois-d&rsquo;Assise de la Longue-Pointe. L&rsquo;expropriation de plus de 300 familles, de terres agricoles et de l&rsquo;\u00e9glise ayant commenc\u00e9 presque deux ans pr\u00e9c\u00e9dent suite \u00e0 l&rsquo;adoption des plans de constructions mit en marche sous Jean Lesage et du Minist\u00e8re du Transport. La derni\u00e8re messe de la paroisse fut c\u00e9l\u00e9br\u00e9e le 26 novembre 1963. Une des firmes de g\u00e9nie-conseil ayant mis la main sur le contrat de construction, Lalonde et Valois connu plus tard sous le nom de Lavalin, SNC-Lavalin est aujourd&rsquo;hui un des plus importants groupes d&rsquo;ing\u00e9nierie et de construction au monde.<\/p>\n<p>Les sept sections de 110 m\u00e8tres de long sur 37 m\u00e8tres de large et huit m\u00e8tres de haut en b\u00e9ton pr\u00e9contraint sont fabriqu\u00e9es dans une cale s\u00e8che am\u00e9nag\u00e9e a m\u00eame le fleuve et finalement mis en place. Je dois avouer que le concept de construction est beaucoup plus compliqu\u00e9 que ces quelques lignes peuvent raconter. Je m&rsquo;excuse mais, ce blogue se veut plus historique que technique apr\u00e8s tout.<\/p>\n<div align=\"center\">\n<figure id=\"attachment_775\" aria-describedby=\"caption-attachment-775\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/tunnel_lhl_cons.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/tunnel_lhl_cons.jpg\" alt=\"Construction\" title=\"Construction\" width=\"550\" height=\"335\" class=\"size-full wp-image-775\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/tunnel_lhl_cons.jpg 550w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/tunnel_lhl_cons-150x91.jpg 150w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/tunnel_lhl_cons-300x182.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a><figcaption id=\"caption-attachment-775\" class=\"wp-caption-text\">Section du Tunnel en cale s\u00e8che<\/figcaption><\/figure>\n<\/div>\n<p>Le pont-tunnel, un des plus grands parcs de la ville, un h\u00f4pital psychiatrique et H\u00e9ritage Montr\u00e9al semble tant bien que mal \u00e0 sauver sa demeure de l&rsquo;\u00eelot Overdale. Mais qui \u00e9tait ce Louis Hippolyte-Lafontaine et pourquoi ce Bouchervillois est-il si important \u00e0 notre historie que l&rsquo;on lui d\u00e9die les plus grands honneurs ? Un des personnages les plus importants de l&rsquo;histoire du Canada et Premier ministre du Canada Uni. Il est connu est important \u00e0 l&rsquo;histoire des Qu\u00e9b\u00e9cois pour avoir fait le premier discours en fran\u00e7ais au parlement qui avec l&rsquo;Acte d&rsquo;union interdisait la langue de Moli\u00e8re dans la basse chambre du gouvernement. En r\u00e9ponse au d\u00e9put\u00e9 Dunn de Toronto qui contesta le discours de Lafontaine en fran\u00e7ais, ce dernier r\u00e9pondit avec un <a href=\"http:\/\/www.pco-bcp.gc.ca\/aia\/index.asp?lang=fra&#038;page=key-cle&#038;doc=intervention-fra.htm\" target=\"_blank\">des discours les plus connus de l&rsquo;histoire du Qu\u00e9bec<\/a>.<\/p>\n<p>La construction ayant n\u00e9cessit\u00e9 250 000 m\u00e8tres cube de b\u00e9ton au co\u00fbt de 75 millions est inaugur\u00e9 le 11 mars 1967, que quelques jours avant l&rsquo;ouverture de Terre des Hommes et de l&rsquo;expo universelle. Daniel Johnson, alors premier ministre louangea avec le Maire Jean Drapeau lors de l&rsquo;inauguration en grandes pompes l&rsquo;ambition et le g\u00e9nie qu\u00e9b\u00e9cois. \u00ab\u00a0Je ne veux pas dire que nous n&rsquo;avons plus rien \u00e0 apprendre, loin de l\u00e0, mais j&rsquo;affirme que nos r\u00e9alisateurs du Qu\u00e9bec sont beaucoup plus que des \u00e9l\u00e8ves\u00a0\u00bb affirmait-il au journal Le Devoir dans son <a href=\"http:\/\/news.google.com\/newspapers?id=FdAxAAAAIBAJ&#038;sjid=3OIFAAAAIBAJ&#038;pg=1362%2C4247450\" target=\"_blank\">\u00e9dition du 13 mars 1967<\/a>. Malheureusement, il \u00e9tait impossible pour M. Johnson de savoir que quelques ann\u00e9es auparavant, ce \u00ab\u00a0g\u00e9nie\u00a0\u00bb qu\u00e9b\u00e9cois avait inaugur\u00e9 des infrastructures comme le Pont Champlain et l&rsquo;\u00e9changeur Turcot qui aujourd&rsquo;hui, tombe en ruine et font peur aux utilisateurs.<\/p>\n<p>Aujourd&rsquo;hui, environ 140 000 v\u00e9hicules par jour utilisent le Pont-Tunnel Louis-Hippolyte-Lafontaine qui est la seule traverse du Fleuve St-Laurent de juridiction provinciale et \u00e0 ce jour est encore le tunnel sous-marin le plus long au Canada. 42 cam\u00e9ras de s\u00e9curit\u00e9 rejoignant un centre de contr\u00f4le ayant deux employ\u00e9s en tout temps assures la s\u00e9curit\u00e9 24h, sept jours sur sept en plus de contr\u00f4ler les niveaux de gaz, les g\u00e9n\u00e9ratrices de service et l&rsquo;\u00e9change d&rsquo;air dans quatre tours de ventilation, la rumeur veut que les tours soient une repr\u00e9sentation symbolique des clochers de l&rsquo;\u00e9glise de la Paroisse St-Fran\u00e7ois-d&rsquo;Assise d\u00e9molie pour la construction du lien routier.<\/p>\n<div align=\"center\">\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"http:\/\/www.youtube.com\/embed\/NLuMK38UZjo?rel=0&amp;hd=1\" frameborder=\"0\" allowfullscreen><\/iframe>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture approximatif de<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>L&rsquo;id\u00e9e du Tunnel sous le Saint-Laurent ne date pas d&rsquo;hier, le journal illustr\u00e9 L&rsquo;opinion Publique publiait les 22 avril 1880 et 29 juillet 1880 des images d&rsquo;un tunnel ferroviaire qui rejoindrait le Village d&rsquo;Hochelaga \u00e0 Longueuil sur la rive sud. Il aura donc fallu attendre jusqu&rsquo;au 11 mars 1967, soit, 87 ans plus tard pour que l&rsquo;ing\u00e9nierie rejoigne le r\u00eave de plusieurs \u00e0 l&rsquo;\u00e9poque.<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/\">Pour lire l&#039;article&#8230;<span class=\"screen-reader-text\">Dossier: Le Pont-tunnel Hippolyte-Lafontaine<\/span><\/a><\/div>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[393,6],"tags":[522,521,529,524,526,527,523,474,525,528,530,520],"class_list":["post-768","post","type-post","status-publish","format-standard","hentry","category-histoire-2","category-urbanisme","tag-cartier","tag-champlain","tag-claude-jutra","tag-grand-trunk","tag-hochelaga","tag-longueuil","tag-mederic-martin","tag-pont","tag-pont-de-glace","tag-rive-sud","tag-suicide","tag-victoria","excerpt","zoom","full-without-featured","even","excerpt-0"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dossier: Le Pont-tunnel Hippolyte-Lafontaine<\/title>\n<meta name=\"description\" content=\"L&#039;id\u00e9e du Tunnel sous le Saint-Laurent ne date pas d&#039;hier, le journal illustr\u00e9 L&#039;opinion Publique publiait les 22 avril 1880 et 29 juillet 1880 des images d&#039;un tunnel ferroviaire qui rejoindrait le Village d&#039;Hochelaga \u00e0 Longueuil sur la rive sud. Il aura donc fallu attendre jusqu&#039;au 11 mars 1967, soit, 87 ans plus tard pour que l&#039;ing\u00e9nierie rejoigne le r\u00eave de plusieurs \u00e0 l&#039;\u00e9poque.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dossier: Le Pont-tunnel Hippolyte-Lafontaine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/\" \/>\n<meta property=\"og:site_name\" content=\"ProposMontr\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proposmontreal\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/proposmontreal\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-13T00:00:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-01T20:40:59+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_avril1880.jpg\" \/>\n<meta name=\"author\" content=\"Martin B\u00e9rub\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@proposmontreal\" \/>\n<meta name=\"twitter:site\" content=\"@ProposMontreal\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin B\u00e9rub\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/dossier-le-pont-tunnel-hippolyte-lafontaine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/dossier-le-pont-tunnel-hippolyte-lafontaine\\\/\"},\"author\":{\"name\":\"Martin B\u00e9rub\u00e9\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#\\\/schema\\\/person\\\/7d7acef09662dd8c0283a456e39b3254\"},\"headline\":\"Dossier: Le Pont-tunnel Hippolyte-Lafontaine\",\"datePublished\":\"2011-11-13T00:00:22+00:00\",\"dateModified\":\"2016-01-01T20:40:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/dossier-le-pont-tunnel-hippolyte-lafontaine\\\/\"},\"wordCount\":814,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/dossier-le-pont-tunnel-hippolyte-lafontaine\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/opinionpublique_avril1880.jpg\",\"keywords\":[\"cartier\",\"champlain\",\"claude jutra\",\"grand-trunk\",\"hochelaga\",\"longueuil\",\"m\u00e9d\u00e9ric-martin\",\"pont\",\"pont de glace\",\"rive-sud\",\"suicide\",\"victoria\"],\"articleSection\":[\"Histoire\",\"Urbanisme\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/dossier-le-pont-tunnel-hippolyte-lafontaine\\\/\",\"url\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/dossier-le-pont-tunnel-hippolyte-lafontaine\\\/\",\"name\":\"Dossier: Le Pont-tunnel Hippolyte-Lafontaine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/dossier-le-pont-tunnel-hippolyte-lafontaine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/dossier-le-pont-tunnel-hippolyte-lafontaine\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/opinionpublique_avril1880.jpg\",\"datePublished\":\"2011-11-13T00:00:22+00:00\",\"dateModified\":\"2016-01-01T20:40:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#\\\/schema\\\/person\\\/7d7acef09662dd8c0283a456e39b3254\"},\"description\":\"L'id\u00e9e du Tunnel sous le Saint-Laurent ne date pas d'hier, le journal illustr\u00e9 L'opinion Publique publiait les 22 avril 1880 et 29 juillet 1880 des images d'un tunnel ferroviaire qui rejoindrait le Village d'Hochelaga \u00e0 Longueuil sur la rive sud. Il aura donc fallu attendre jusqu'au 11 mars 1967, soit, 87 ans plus tard pour que l'ing\u00e9nierie rejoigne le r\u00eave de plusieurs \u00e0 l'\u00e9poque.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/dossier-le-pont-tunnel-hippolyte-lafontaine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/dossier-le-pont-tunnel-hippolyte-lafontaine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/dossier-le-pont-tunnel-hippolyte-lafontaine\\\/#primaryimage\",\"url\":\"http:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/opinionpublique_avril1880.jpg\",\"contentUrl\":\"http:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2011\\\/11\\\/opinionpublique_avril1880.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/dossier-le-pont-tunnel-hippolyte-lafontaine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/proposmontreal.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dossier: Le Pont-tunnel Hippolyte-Lafontaine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#website\",\"url\":\"https:\\\/\\\/proposmontreal.com\\\/\",\"name\":\"ProposMontr\u00e9al\",\"description\":\"Histoire, Urbanisme, Architecture et Opinions.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proposmontreal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#\\\/schema\\\/person\\\/7d7acef09662dd8c0283a456e39b3254\",\"name\":\"Martin B\u00e9rub\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g\",\"caption\":\"Martin B\u00e9rub\u00e9\"},\"description\":\"Amoureux de Montr\u00e9al, fascin\u00e9 par l'histoire de la ville, son urbanisme et sa toponymie, ni historien ni sp\u00e9cialiste du sujet, Martin n'\u00e9tait m\u00eame pas n\u00e9 \u00e0 l'\u00e9poque de 99% des sujets discut\u00e9s de ce site. Il aime trouver des r\u00e9ponses aux questions qui sont pos\u00e9es. Les billets que vous lisez ne sont que les r\u00e9sultats de la qu\u00eate vers des r\u00e9ponses et le besoin de partager.\",\"sameAs\":[\"http:\\\/\\\/proposmontreal.com\",\"https:\\\/\\\/www.facebook.com\\\/proposmontreal\",\"https:\\\/\\\/x.com\\\/proposmontreal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dossier: Le Pont-tunnel Hippolyte-Lafontaine","description":"L'id\u00e9e du Tunnel sous le Saint-Laurent ne date pas d'hier, le journal illustr\u00e9 L'opinion Publique publiait les 22 avril 1880 et 29 juillet 1880 des images d'un tunnel ferroviaire qui rejoindrait le Village d'Hochelaga \u00e0 Longueuil sur la rive sud. Il aura donc fallu attendre jusqu'au 11 mars 1967, soit, 87 ans plus tard pour que l'ing\u00e9nierie rejoigne le r\u00eave de plusieurs \u00e0 l'\u00e9poque.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/","og_locale":"fr_FR","og_type":"article","og_title":"Dossier: Le Pont-tunnel Hippolyte-Lafontaine","og_url":"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/","og_site_name":"ProposMontr\u00e9al","article_publisher":"https:\/\/www.facebook.com\/proposmontreal","article_author":"https:\/\/www.facebook.com\/proposmontreal","article_published_time":"2011-11-13T00:00:22+00:00","article_modified_time":"2016-01-01T20:40:59+00:00","og_image":[{"url":"http:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_avril1880.jpg","type":"","width":"","height":""}],"author":"Martin B\u00e9rub\u00e9","twitter_card":"summary_large_image","twitter_creator":"@proposmontreal","twitter_site":"@ProposMontreal","twitter_misc":{"\u00c9crit par":"Martin B\u00e9rub\u00e9","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/#article","isPartOf":{"@id":"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/"},"author":{"name":"Martin B\u00e9rub\u00e9","@id":"https:\/\/proposmontreal.com\/#\/schema\/person\/7d7acef09662dd8c0283a456e39b3254"},"headline":"Dossier: Le Pont-tunnel Hippolyte-Lafontaine","datePublished":"2011-11-13T00:00:22+00:00","dateModified":"2016-01-01T20:40:59+00:00","mainEntityOfPage":{"@id":"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/"},"wordCount":814,"commentCount":0,"image":{"@id":"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/#primaryimage"},"thumbnailUrl":"http:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_avril1880.jpg","keywords":["cartier","champlain","claude jutra","grand-trunk","hochelaga","longueuil","m\u00e9d\u00e9ric-martin","pont","pont de glace","rive-sud","suicide","victoria"],"articleSection":["Histoire","Urbanisme"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/","url":"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/","name":"Dossier: Le Pont-tunnel Hippolyte-Lafontaine","isPartOf":{"@id":"https:\/\/proposmontreal.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/#primaryimage"},"image":{"@id":"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/#primaryimage"},"thumbnailUrl":"http:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_avril1880.jpg","datePublished":"2011-11-13T00:00:22+00:00","dateModified":"2016-01-01T20:40:59+00:00","author":{"@id":"https:\/\/proposmontreal.com\/#\/schema\/person\/7d7acef09662dd8c0283a456e39b3254"},"description":"L'id\u00e9e du Tunnel sous le Saint-Laurent ne date pas d'hier, le journal illustr\u00e9 L'opinion Publique publiait les 22 avril 1880 et 29 juillet 1880 des images d'un tunnel ferroviaire qui rejoindrait le Village d'Hochelaga \u00e0 Longueuil sur la rive sud. Il aura donc fallu attendre jusqu'au 11 mars 1967, soit, 87 ans plus tard pour que l'ing\u00e9nierie rejoigne le r\u00eave de plusieurs \u00e0 l'\u00e9poque.","breadcrumb":{"@id":"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/#primaryimage","url":"http:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_avril1880.jpg","contentUrl":"http:\/\/proposmontreal.com\/wp-content\/uploads\/2011\/11\/opinionpublique_avril1880.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/proposmontreal.com\/index.php\/dossier-le-pont-tunnel-hippolyte-lafontaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/proposmontreal.com\/"},{"@type":"ListItem","position":2,"name":"Dossier: Le Pont-tunnel Hippolyte-Lafontaine"}]},{"@type":"WebSite","@id":"https:\/\/proposmontreal.com\/#website","url":"https:\/\/proposmontreal.com\/","name":"ProposMontr\u00e9al","description":"Histoire, Urbanisme, Architecture et Opinions.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proposmontreal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/proposmontreal.com\/#\/schema\/person\/7d7acef09662dd8c0283a456e39b3254","name":"Martin B\u00e9rub\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g","caption":"Martin B\u00e9rub\u00e9"},"description":"Amoureux de Montr\u00e9al, fascin\u00e9 par l'histoire de la ville, son urbanisme et sa toponymie, ni historien ni sp\u00e9cialiste du sujet, Martin n'\u00e9tait m\u00eame pas n\u00e9 \u00e0 l'\u00e9poque de 99% des sujets discut\u00e9s de ce site. Il aime trouver des r\u00e9ponses aux questions qui sont pos\u00e9es. Les billets que vous lisez ne sont que les r\u00e9sultats de la qu\u00eate vers des r\u00e9ponses et le besoin de partager.","sameAs":["http:\/\/proposmontreal.com","https:\/\/www.facebook.com\/proposmontreal","https:\/\/x.com\/proposmontreal"]}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts\/768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/comments?post=768"}],"version-history":[{"count":7,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts\/768\/revisions"}],"predecessor-version":[{"id":3972,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts\/768\/revisions\/3972"}],"wp:attachment":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/media?parent=768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/categories?post=768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/tags?post=768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}