{"id":3997,"date":"2016-01-04T08:08:58","date_gmt":"2016-01-04T13:08:58","guid":{"rendered":"http:\/\/proposmontreal.com\/?p=3997"},"modified":"2022-07-15T12:15:39","modified_gmt":"2022-07-15T16:15:39","slug":"une-tour-qui-aurait-change-lhistoire","status":"publish","type":"post","link":"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/","title":{"rendered":"Une tour  qui aurait chang\u00e9 l&rsquo;histoire."},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture approximatif de<\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p>Qu\u2019ont en commun la tour Eiffel de Paris, la Space Needle de Seattle et la Biosph\u00e8re de Montr\u00e9al? Elles ont toutes les trois \u00e9t\u00e9 \u00e9rig\u00e9es durant une exposition internationale. Montr\u00e9al a profit\u00e9 de son Expo avec des retomb\u00e9es architecturales hors du commun. M\u00eame si la majorit\u00e9 des b\u00e2timents ont malheureusement disparu, plusieurs restent encore utilis\u00e9s aujourd\u2019hui. Par exemple, la Biosph\u00e8re est notre tour Eiffel et l\u2019architecte Buckminster Fuller n&rsquo;a pas la m\u00eame notori\u00e9t\u00e9 dans la culture populaire qu&rsquo;un Moshe Safdie pour Habitat 67. Il est aussi possible de nommer le Casino et le Pavillon du Canada qui sont encore bien utilis\u00e9s de nos jours. Que me diriez-vous si je disais que la tour du Stade Olympique est \u00e9galement un restant de l\u2019Expo?<\/p>\n<p>Termin\u00e9 exactement 20 ans apr\u00e8s les \u00e9v\u00e9nements de 1967, la tour du Stade est probablement une des ic\u00f4nes incontestables de la ville, incluant les rappels navrants de sa construction. Il est difficile de nier que la tour n\u2019a pas d\u2019impact important sur la ligne d\u2019horizon de la ville. C\u2019est la plus grande tour inclin\u00e9e du monde apr\u00e8s tout et je crois que nous devrions en \u00eatre plus fier que nous le somme en v\u00e9rit\u00e9. Mais cette tour a un pass\u00e9 m\u00e9connu et on doit revenir au tout d\u00e9but des pr\u00e9parations pour l\u2019exposition universelle pour voir l\u2019id\u00e9e d\u2019une grande tour germer dans la t\u00eate du Maire Drapeau.<\/p>\n<p>Le maire tient obstin\u00e9ment \u00e0 voir une tour, une \u0153uvre phare qui changerait cette ligne d\u2019horizon encore relativement nouvelle. Au d\u00e9but des ann\u00e9es 60, Montr\u00e9al poss\u00e8de quatre gratte-ciel qui d\u00e9passent les 125 m\u00e8tres, la Tour de la Bourse, la Place Ville-Marie, la tour CIBC et la CIL House (Tour Telus) et elles sont les plus hautes du pays. Montr\u00e9al est \u00e0 ce moment dans l\u2019histoire encore la m\u00e9tropole du Canada et Drapeau souhaite ajouter \u00e0 cette domination. Comme j\u2019ai d\u00e9j\u00e0 mentionn\u00e9 <a href=\"https:\/\/proposmontreal.com\/index.php\/20-faits-sur-montreal-4e-edition\/\" target=\"_blank\" rel=\"noopener\">dans un autre texte<\/a>, il convainc m\u00eame les autorit\u00e9s de Paris de d\u00e9m\u00e9nager la tour Eiffel le temps de l\u2019Expo. <\/p>\n<div align=\"center\">\n<figure id=\"attachment_4008\" aria-describedby=\"caption-attachment-4008\" style=\"width: 451px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/ledevoir.jpg\" alt=\"Titre du quotidien Le Devoir  du 11 d\u00e9cembre 1964.\" width=\"451\" height=\"774\" class=\"size-full wp-image-4008\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/ledevoir.jpg 451w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/ledevoir-87x150.jpg 87w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/ledevoir-175x300.jpg 175w\" sizes=\"auto, (max-width: 451px) 100vw, 451px\" \/><figcaption id=\"caption-attachment-4008\" class=\"wp-caption-text\">Titre du quotidien Le Devoir  du 11 d\u00e9cembre 1964.<\/figcaption><\/figure>\n<\/div>\n<p>M. le Maire r\u00eave d\u2019une tour depuis belle lurette, ayant m\u00eame d\u00e9j\u00e0 voulu \u00e9riger une de ses structures directement sur le mont Royal, heureusement ce projet tomba \u00e0 l\u2019eau rapidement. Toutefois, une autre id\u00e9e germait d\u00e9j\u00e0 dans sa t\u00eate. En d\u00e9cembre 1964 avec le soutien moral de Lucien Saulnier, son bras droit \u00e0 l\u2019ex\u00e9cutif de la ville et des \u00e9lus de la ville de Paris, Drapeau pr\u00e9sente au conseil municipal une tour de 325 m en honneur des fondateurs de Montr\u00e9al. Durant la proposition du projet, minutes avant le d\u00e9voilement de la maquette, Drapeau mentionne que suite \u00e0 2e Grande Guerre, Montr\u00e9al n\u2019a pas \u00e9t\u00e9 en mesure de f\u00eater ad\u00e9quatement son 300e anniversaire et qu\u2019une tour de 325 m pour le 325e n\u2019est que d\u2019une logique sans faille. \u00c9valu\u00e9e \u00e0 20 millions pour la construction, la tour doit s\u2019autofinancer avec de l\u2019espace locatif et les revenus d&rsquo;une plate-forme d\u2019observation pr\u00e9vue au haut de la structure. <\/p>\n<p>La Compagnie de l\u2019expo 67 avec Pierre Dupuy en t\u00eate n\u2019est pas chaude \u00e0 l\u2019id\u00e9e d\u2019une tour, une id\u00e9e qu\u2019ils avaient eux-m\u00eames repouss\u00e9e lors de la conception du projet en 1963. Ancien avocat, le maire a la parole facile, \u00ab Nous ne pouvons oublier ceux qui sont venus ici fonder notre ville, il nous faut un monument \u00e0 leur m\u00e9moire. Montr\u00e9al \u00e9tant la m\u00e9tropole, il est impensable qu\u2019on \u00e9l\u00e8ve ce monument en marge de l\u2019Expo qui elle-m\u00eame est un hommage \u00e0 ceux qui ont fait le Canada \u00bb. Tout \u00e9tait pens\u00e9 pour plaire au plus de gens possible. La pointe est de l\u2019\u00eele Ronde ne devait que servir d\u2019un espace gazonn\u00e9, un parc, rien de mieux. Ce fut un des d\u00e9tails qui r\u00e9ussira \u00e0 convaincre la compagnie de l\u2019Expo d\u2019approuver le projet dans leur giron. <\/p>\n<div align=\"center\">\n<figure id=\"attachment_3161\" aria-describedby=\"caption-attachment-3161\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2014\/11\/montreal-paris.jpg\" alt=\"Maquettes de la Tour Paris-Montr\u00e9al avec Jean Drapeau\" width=\"550\" height=\"700\" class=\"size-full wp-image-3161\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2014\/11\/montreal-paris.jpg 550w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2014\/11\/montreal-paris-117x150.jpg 117w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2014\/11\/montreal-paris-235x300.jpg 235w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><figcaption id=\"caption-attachment-3161\" class=\"wp-caption-text\">Maquettes de la Tour Paris-Montr\u00e9al avec Jean Drapeau<\/figcaption><\/figure>\n<\/div>\n<p>Comme quoi les choses n\u2019ont pas chang\u00e9 \u00e9norm\u00e9ment depuis 50 ans. Qui dit projet \u00e0 Montr\u00e9al, dit automatiquement r\u00e9sistance. D\u2019abord, c\u2019est la bourgeoisie anglaise qui voit d\u2019un mauvais \u0153il la cr\u00e9ation d\u2019un monument par un architecte fran\u00e7ais, en honneur des fondateurs fran\u00e7ais. C\u2019est aussi l\u2019ordre des architectes du Qu\u00e9bec qui ne comprennent tout simplement pas pourquoi c&rsquo;est justement un fran\u00e7ais qui serait responsable du dessin final de cette tour au Qu\u00e9bec. Bien s\u00fbr, les blagues comparant l\u2019immeuble \u00e0 une branche de c\u00e9leri ou \u00e0 l\u2019anatomie du m\u00e2le sont elles aussi bien pr\u00e9sentes, en g\u00e9n\u00e9ral, la tour est bien accept\u00e9e du public. <\/p>\n<p>Le projet a du plomb dans l\u2019aile assez rapidement. La date limite pour la construction est plac\u00e9e pour la fin de juin 1965 et l\u2019appel d\u2019offres est finalement plac\u00e9 pour trouver un entrepreneur pr\u00eat \u00e0 prendre la charge du projet. Le 3 juin, trois groupes d\u00e9posent leurs soumissions, variant entre 23 et 24,5 millions, elles d\u00e9passent d\u00e9j\u00e0 les 20 millions originalement promis lors de son d\u00e9voilement. Les co\u00fbts d\u00e9passant de huit \u00e0 dix millions les estimations initiales font peur aux autorit\u00e9s de Montr\u00e9al. La ville de Paris commence fortement \u00e0 douter de la construction de ce monument, r\u00e9p\u00e9tant \u00e0 maintes reprises qu\u2019il est impossible de voir leur part initiale de 10 millions de dollars \u00eatre major\u00e9e. <\/p>\n<p>L&rsquo;aventure sera de courte dur\u00e9e, le 8 juillet 1965, le bureau du maire d\u00e9pose un communiqu\u00e9 affirmant que le projet de tour est simplement abandonn\u00e9. Tous l\u2019apprennent du m\u00eame coup, autant la ville de Paris que les gestionnaires de l\u2019Expo. C\u2019est la surprise totale et comme si tout \u00e9tait orchestr\u00e9 ni Drapeau ni Saulnier ne sont disponibles pour r\u00e9pondre aux questions des journalistes. Le Maire devait faire face \u00e0 l\u2019\u00e9vidence, il serait pratiquement impossible que le projet soit auto financ\u00e9e et les d\u00e9passements de co\u00fbts ne feraient qu\u2019augmenter \u00e0 mesure que la date de la premi\u00e8re pellet\u00e9e serait repouss\u00e9e. \u00ab Personnellement, je continue de croire \u00e0 la rentabilit\u00e9 du projet \u00e0 ce nouveau prix. Mais je dois admettre qu\u2019elle devient moins \u00e9vidente \u00e0 l\u2019opinion publique, vu les affirmations que j\u2019ai d\u00fb, depuis d\u00e9cembre dernier, r\u00e9it\u00e9rer voulant que ce monument se paierait par lui-m\u00eame sur la base de 20 millions de dollars et ne co\u00fbterait rien au budget municipal \u00bb. Suite au communiqu\u00e9, ce sera le silence de la part de ce dernier, fatigu\u00e9 et d\u00e9moralis\u00e9, il sera hospitalis\u00e9 pour deux semaines peu apr\u00e8s le retrait au projet. <\/p>\n<div align=\"center\">\n<figure id=\"attachment_4004\" aria-describedby=\"caption-attachment-4004\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/TourSaulnier.jpg\" alt=\"Tour propos\u00e9e pour remplacer la Tour Paris-Montr\u00e9al. \" width=\"600\" height=\"750\" class=\"size-full wp-image-4004\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/TourSaulnier.jpg 600w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/TourSaulnier-120x150.jpg 120w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/TourSaulnier-240x300.jpg 240w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-4004\" class=\"wp-caption-text\">Tour propos\u00e9e pour remplacer la Tour Paris-Montr\u00e9al.<\/figcaption><\/figure>\n<\/div>\n<p>La compagnie canadienne de l\u2019Expo, d\u2019abord r\u00e9fractaire \u00e0 l\u2019id\u00e9e, essaie maintenant de sauver le projet en ouvrant la porte \u00e0 de nouvelles tours, moins co\u00fbteuses, moins hautes, moins grandioses, mais en vain, l\u2019Expo n\u2019aura pas de tour. Montr\u00e9al n\u2019a m\u00eame pas de pavillon \u00e0 son nom lors de l\u2019Expo, oui elle en est la ville h\u00f4tesse, mais n\u2019est pas autrement repr\u00e9sent\u00e9e.<\/p>\n<div align=\"center\">\n<figure id=\"attachment_4002\" aria-describedby=\"caption-attachment-4002\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/maquette-stade-olympique.jpg\" alt=\"Maquette du Stade olympique d\u00e9voil\u00e9 en 1972 \" width=\"600\" height=\"387\" class=\"size-full wp-image-4002\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/maquette-stade-olympique.jpg 600w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/maquette-stade-olympique-150x97.jpg 150w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/maquette-stade-olympique-300x194.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-4002\" class=\"wp-caption-text\">Maquette du Stade olympique d\u00e9voil\u00e9 en 1972<br \/><\/figcaption><\/figure>\n<\/div>\n<p>D\u00e9pla\u00e7ons-nous le 6 avril 1972 lors du d\u00e9voilement de la maquette du futur Stade Olympique, tel un clin d\u2019\u0153il, une tour inclin\u00e9e fera son apparition dans le ciel de Montr\u00e9al. Elle est coup\u00e9e de moiti\u00e9 \u00e0 165 m\u00e8tres et encore sous le crayon d\u2019un architecte fran\u00e7ais, Drapeau l&rsquo;aura finalement sa tour. Une fois de plus, les \u00e9toiles ne sont pas align\u00e9es. La plan\u00e8te en entier n&rsquo;admirera pas de tour sur Montr\u00e9al puisque la construction du stade ne pourra \u00eatre termin\u00e9e \u00e0 temps pour le d\u00e9but des jeux. Une honte qui ne sera pas r\u00e9par\u00e9e avant 1987, ayant d\u00e9pass\u00e9e les co\u00fbts \u00e0 coup de centaines de millions et pay\u00e9e en grande partie par les contribuables. Montr\u00e9al est \u00e0 son plus bas \u00e0 la fin des ann\u00e9es 70. Selon les experts, l\u2019arriv\u00e9e du PQ a cr\u00e9\u00e9 une frousse majeure aux investisseurs anglo-saxons qui encore \u00e0 l\u2019\u00e9poque poss\u00e9daient le gros du pouvoir. C&rsquo;est sans compter la corruption au c\u0153ur m\u00eame du boom de la construction entre 1965 et 1976 ainsi que cette image de stade incomplet pour un des \u00e9v\u00e9nements les plus importants de la plan\u00e8te qui finalement couleront Montr\u00e9al au d\u00e9triment de Toronto qui tr\u00f4ne comme m\u00e9tropole du pays.<\/p>\n<div align=\"center\">\n<figure id=\"attachment_4000\" aria-describedby=\"caption-attachment-4000\" style=\"width: 586px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/epreuve-tour-586x1024.jpg\" alt=\"Int\u00e9rieur de la tour Montr\u00e9al-Paris. \" width=\"586\" height=\"1024\" class=\"size-large wp-image-4000\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/epreuve-tour-586x1024.jpg 586w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/epreuve-tour-86x150.jpg 86w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/epreuve-tour-172x300.jpg 172w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/epreuve-tour.jpg 600w\" sizes=\"auto, (max-width: 586px) 100vw, 586px\" \/><figcaption id=\"caption-attachment-4000\" class=\"wp-caption-text\">Int\u00e9rieur de la tour Montr\u00e9al-Paris.<\/figcaption><\/figure>\n<\/div>\n<p>Il faudra attendre jusqu&rsquo;en 2017 et apr\u00e8s une mise \u00e0 niveau majeure pour voir un locataire important installer ses p\u00e9nates dans la tour du stade, soit plus de 50 ans apr\u00e8s l&rsquo;annonce d&rsquo;une tour par le maire Drapeau sur ses nouvelles \u00eeles. Octobre 2015, Le Groupe Desjardins annonce \u00e0 la plus grande surprise de tous que l&rsquo;entreprise r\u00e9unira entre 1300 et 1800 employ\u00e9s \u00e9parpill\u00e9s dans l&rsquo;est de la ville dans des bureaux qui seront am\u00e9nag\u00e9s \u00e0 l&rsquo;int\u00e9rieur du m\u00e2t. Si nous devons nous fier \u00e0 l&rsquo;histoire, je vais devoir attendre que les premiers employ\u00e9s croisent la porte du funiculaire pour me r\u00e9jouir.  <\/p>\n<p>Qui sait ce qu\u2019aurait \u00e9t\u00e9 notre ville avec la tour Paris-Montr\u00e9al dans son \u00ab\u00a0skyline\u00a0\u00bb? Les touristes seraient-ils aussi attir\u00e9s par ce monument qu\u2019ils le sont par la tour Eiffel comme r\u00eavait Drapeau? Peut-\u00eatre n\u2019aurions jamais eu <a href=\"https:\/\/proposmontreal.com\/index.php\/une-hauteur-limite\/\" target=\"_blank\" rel=\"noopener\">cette hauteur limite<\/a> pour les nouvelles constructions? Est-ce que ce besoin maladif finalement assouvi du maire pour une tour aurait fait que le Stade Olympique soit plus modeste et imaginons que ce stade avait \u00e9t\u00e9 compl\u00e9t\u00e9 \u00e0 temps pour les Olympiques et ce, sans nous avoir co\u00fbt\u00e9 plus d\u2019un milliard de dollars d\u00fb \u00e0 la mauvaise gestion de sa construction. On ne le saura jamais, cependant, une chose est certaine, cette tour aurait vraisemblablement chang\u00e9 le cours de l\u2019histoire.<\/p>\n<p>M\u00eame si j&rsquo;ai fait mes recherches sur le sujet, je dois donner un gros morceau du cr\u00e9dit \u00e0 M. Roger La Roche qui dans <a href=\"https:\/\/dl.dropboxusercontent.com\/u\/13503829\/Fiche%20Tour%20Paris-Mtl_Final_WEB.pdf\" target=\"_blank\" rel=\"noopener\">ce document PDF<\/a> mentionne toutes les grandes lignes de fa\u00e7on tr\u00e8s d\u00e9taill\u00e9s la saga de la tour Paris-Montr\u00e9al et qui m&rsquo;a grandement aid\u00e9 dans la recherche de sources dans les quotidiens et pour les dates. Il m&rsquo;a donner la permission de m&rsquo;en inspirer et rendons \u00e0 C\u00e9sar ce qui appartient \u00e0 C\u00e9sar. J&rsquo;avais \u00e9galement d\u00e9j\u00e0 parl\u00e9 de la tour sans vraiment entrer dans les d\u00e9tails sur <a href=\"https:\/\/proposmontreal.com\/index.php\/les-fetes-de-montreal\/\" target=\"_blank\" rel=\"noopener\">un article des legs pass\u00e9s des f\u00eates de Montr\u00e9al<\/a>.<\/p>\n<div align=\"center\">\n<figure id=\"attachment_4005\" aria-describedby=\"caption-attachment-4005\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/maquette-tour2.jpg\" alt=\"Maquette\" width=\"600\" height=\"552\" class=\"size-full wp-image-4005\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/maquette-tour2.jpg 600w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/maquette-tour2-150x138.jpg 150w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/maquette-tour2-300x276.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-4005\" class=\"wp-caption-text\">Maquette<\/figcaption><\/figure>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture approximatif de<\/span> <span class=\"rt-time\"> 6<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>Montr\u00e9al de 2016 aurait pu \u00eatre bien diff\u00e9rente et une seule tour aurait sauv\u00e9 la m\u00e9tropole du Canada. Comment? Je vous l&rsquo;explique ici. <\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/\">Pour lire l&#039;article&#8230;<span class=\"screen-reader-text\">Une tour  qui aurait chang\u00e9 l&rsquo;histoire.<\/span><\/a><\/div>\n","protected":false},"author":2,"featured_media":4005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1725,393],"tags":[1472,1194,893,1471,1473,449,1470],"class_list":["post-3997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-architecture","category-histoire-2","tag-charles-de-gaulle","tag-expo-67","tag-jean-drapeau","tag-lucien-saulnier","tag-paris-montreal","tag-stade-olympique","tag-tour-montreal-paris","excerpt","zoom","full-without-featured","even","excerpt-0"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La tour qui aurait chang\u00e9 l&#039;histoire<\/title>\n<meta name=\"description\" content=\"Montr\u00e9al de 2016 aurait pu \u00eatre bien diff\u00e9rente et une seule tour aurait sauv\u00e9 la m\u00e9tropole du Canada. Comment? Je vous l&#039;explique ici.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La tour qui aurait chang\u00e9 l&#039;histoire\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/\" \/>\n<meta property=\"og:site_name\" content=\"ProposMontr\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proposmontreal\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/proposmontreal\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-04T13:08:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-15T16:15:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/maquette-tour2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"552\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Martin B\u00e9rub\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@proposmontreal\" \/>\n<meta name=\"twitter:site\" content=\"@ProposMontreal\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin B\u00e9rub\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/une-tour-qui-aurait-change-lhistoire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/une-tour-qui-aurait-change-lhistoire\\\/\"},\"author\":{\"name\":\"Martin B\u00e9rub\u00e9\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#\\\/schema\\\/person\\\/7d7acef09662dd8c0283a456e39b3254\"},\"headline\":\"Une tour qui aurait chang\u00e9 l&rsquo;histoire.\",\"datePublished\":\"2016-01-04T13:08:58+00:00\",\"dateModified\":\"2022-07-15T16:15:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/une-tour-qui-aurait-change-lhistoire\\\/\"},\"wordCount\":1864,\"image\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/une-tour-qui-aurait-change-lhistoire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/maquette-tour2.jpg\",\"keywords\":[\"Charles de Gaulle\",\"Expo 67\",\"jean-Drapeau\",\"Lucien Saulnier\",\"Paris-Montr\u00e9al\",\"Stade Olympique\",\"tour Montreal-Paris\"],\"articleSection\":[\"Architecture\",\"Histoire\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/une-tour-qui-aurait-change-lhistoire\\\/\",\"url\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/une-tour-qui-aurait-change-lhistoire\\\/\",\"name\":\"La tour qui aurait chang\u00e9 l'histoire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/une-tour-qui-aurait-change-lhistoire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/une-tour-qui-aurait-change-lhistoire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/maquette-tour2.jpg\",\"datePublished\":\"2016-01-04T13:08:58+00:00\",\"dateModified\":\"2022-07-15T16:15:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#\\\/schema\\\/person\\\/7d7acef09662dd8c0283a456e39b3254\"},\"description\":\"Montr\u00e9al de 2016 aurait pu \u00eatre bien diff\u00e9rente et une seule tour aurait sauv\u00e9 la m\u00e9tropole du Canada. Comment? Je vous l'explique ici.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/une-tour-qui-aurait-change-lhistoire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/une-tour-qui-aurait-change-lhistoire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/une-tour-qui-aurait-change-lhistoire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/maquette-tour2.jpg\",\"contentUrl\":\"https:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/maquette-tour2.jpg\",\"width\":600,\"height\":552,\"caption\":\"Maquette de la tour Montr\u00e9al-Paris\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/une-tour-qui-aurait-change-lhistoire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/proposmontreal.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une tour qui aurait chang\u00e9 l&rsquo;histoire.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#website\",\"url\":\"https:\\\/\\\/proposmontreal.com\\\/\",\"name\":\"ProposMontr\u00e9al\",\"description\":\"Histoire, Urbanisme, Architecture et Opinions.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proposmontreal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#\\\/schema\\\/person\\\/7d7acef09662dd8c0283a456e39b3254\",\"name\":\"Martin B\u00e9rub\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g\",\"caption\":\"Martin B\u00e9rub\u00e9\"},\"description\":\"Amoureux de Montr\u00e9al, fascin\u00e9 par l'histoire de la ville, son urbanisme et sa toponymie, ni historien ni sp\u00e9cialiste du sujet, Martin n'\u00e9tait m\u00eame pas n\u00e9 \u00e0 l'\u00e9poque de 99% des sujets discut\u00e9s de ce site. Il aime trouver des r\u00e9ponses aux questions qui sont pos\u00e9es. Les billets que vous lisez ne sont que les r\u00e9sultats de la qu\u00eate vers des r\u00e9ponses et le besoin de partager.\",\"sameAs\":[\"http:\\\/\\\/proposmontreal.com\",\"https:\\\/\\\/www.facebook.com\\\/proposmontreal\",\"https:\\\/\\\/x.com\\\/proposmontreal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La tour qui aurait chang\u00e9 l'histoire","description":"Montr\u00e9al de 2016 aurait pu \u00eatre bien diff\u00e9rente et une seule tour aurait sauv\u00e9 la m\u00e9tropole du Canada. Comment? Je vous l'explique ici.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/","og_locale":"fr_FR","og_type":"article","og_title":"La tour qui aurait chang\u00e9 l'histoire","og_url":"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/","og_site_name":"ProposMontr\u00e9al","article_publisher":"https:\/\/www.facebook.com\/proposmontreal","article_author":"https:\/\/www.facebook.com\/proposmontreal","article_published_time":"2016-01-04T13:08:58+00:00","article_modified_time":"2022-07-15T16:15:39+00:00","og_image":[{"width":600,"height":552,"url":"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/maquette-tour2.jpg","type":"image\/jpeg"}],"author":"Martin B\u00e9rub\u00e9","twitter_card":"summary_large_image","twitter_creator":"@proposmontreal","twitter_site":"@ProposMontreal","twitter_misc":{"\u00c9crit par":"Martin B\u00e9rub\u00e9","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/#article","isPartOf":{"@id":"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/"},"author":{"name":"Martin B\u00e9rub\u00e9","@id":"https:\/\/proposmontreal.com\/#\/schema\/person\/7d7acef09662dd8c0283a456e39b3254"},"headline":"Une tour qui aurait chang\u00e9 l&rsquo;histoire.","datePublished":"2016-01-04T13:08:58+00:00","dateModified":"2022-07-15T16:15:39+00:00","mainEntityOfPage":{"@id":"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/"},"wordCount":1864,"image":{"@id":"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/#primaryimage"},"thumbnailUrl":"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/maquette-tour2.jpg","keywords":["Charles de Gaulle","Expo 67","jean-Drapeau","Lucien Saulnier","Paris-Montr\u00e9al","Stade Olympique","tour Montreal-Paris"],"articleSection":["Architecture","Histoire"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/","url":"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/","name":"La tour qui aurait chang\u00e9 l'histoire","isPartOf":{"@id":"https:\/\/proposmontreal.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/#primaryimage"},"image":{"@id":"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/#primaryimage"},"thumbnailUrl":"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/maquette-tour2.jpg","datePublished":"2016-01-04T13:08:58+00:00","dateModified":"2022-07-15T16:15:39+00:00","author":{"@id":"https:\/\/proposmontreal.com\/#\/schema\/person\/7d7acef09662dd8c0283a456e39b3254"},"description":"Montr\u00e9al de 2016 aurait pu \u00eatre bien diff\u00e9rente et une seule tour aurait sauv\u00e9 la m\u00e9tropole du Canada. Comment? Je vous l'explique ici.","breadcrumb":{"@id":"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/#primaryimage","url":"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/maquette-tour2.jpg","contentUrl":"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/maquette-tour2.jpg","width":600,"height":552,"caption":"Maquette de la tour Montr\u00e9al-Paris"},{"@type":"BreadcrumbList","@id":"https:\/\/proposmontreal.com\/index.php\/une-tour-qui-aurait-change-lhistoire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/proposmontreal.com\/"},{"@type":"ListItem","position":2,"name":"Une tour qui aurait chang\u00e9 l&rsquo;histoire."}]},{"@type":"WebSite","@id":"https:\/\/proposmontreal.com\/#website","url":"https:\/\/proposmontreal.com\/","name":"ProposMontr\u00e9al","description":"Histoire, Urbanisme, Architecture et Opinions.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proposmontreal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/proposmontreal.com\/#\/schema\/person\/7d7acef09662dd8c0283a456e39b3254","name":"Martin B\u00e9rub\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g","caption":"Martin B\u00e9rub\u00e9"},"description":"Amoureux de Montr\u00e9al, fascin\u00e9 par l'histoire de la ville, son urbanisme et sa toponymie, ni historien ni sp\u00e9cialiste du sujet, Martin n'\u00e9tait m\u00eame pas n\u00e9 \u00e0 l'\u00e9poque de 99% des sujets discut\u00e9s de ce site. Il aime trouver des r\u00e9ponses aux questions qui sont pos\u00e9es. Les billets que vous lisez ne sont que les r\u00e9sultats de la qu\u00eate vers des r\u00e9ponses et le besoin de partager.","sameAs":["http:\/\/proposmontreal.com","https:\/\/www.facebook.com\/proposmontreal","https:\/\/x.com\/proposmontreal"]}]}},"jetpack_featured_media_url":"https:\/\/proposmontreal.com\/wp-content\/uploads\/2016\/01\/maquette-tour2.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts\/3997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/comments?post=3997"}],"version-history":[{"count":3,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts\/3997\/revisions"}],"predecessor-version":[{"id":7471,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts\/3997\/revisions\/7471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/media\/4005"}],"wp:attachment":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/media?parent=3997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/categories?post=3997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/tags?post=3997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}