{"id":1617,"date":"2013-03-28T11:04:36","date_gmt":"2013-03-28T15:04:36","guid":{"rendered":"http:\/\/proposmontreal.com\/?p=1617"},"modified":"2013-04-10T07:25:05","modified_gmt":"2013-04-10T11:25:05","slug":"tour-du-spectrum","status":"publish","type":"post","link":"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/","title":{"rendered":"Tour du Spectrum."},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture approximatif de<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p>Le 18 octobre 2008 s&rsquo;\u00e9teignaient pour de bon les lumi\u00e8res de No\u00ebl sur les murs du Spectrum et depuis, un terrain vague cl\u00f4tur\u00e9 en gravier reste le seul souvenir qu&rsquo;un moment donn\u00e9, les meilleurs chanteurs et groupes du Qu\u00e9bec se produisait \u00e0 cet endroit. Faire le Spectrum \u00e9tait presque aussi important que faire le Forum. Il reste quand m\u00eame ironique que le Quartier des Spectacles manquent une des salles les plus mythiques de la m\u00e9tropole.<\/p>\n<div align=\"center\">\n<figure id=\"attachment_1626\" aria-describedby=\"caption-attachment-1626\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.flickr.com\/photos\/61779764@N00\/2874803422\/lightbox\/\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/spectrum.jpg\" alt=\"Les derni\u00e8res heures du Spectrum, Photo: Marc-A. G\" width=\"550\" height=\"280\" class=\"size-full wp-image-1626\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/spectrum.jpg 550w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/spectrum-150x76.jpg 150w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/spectrum-300x152.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a><figcaption id=\"caption-attachment-1626\" class=\"wp-caption-text\">Les derni\u00e8res heures du Spectrum, Photo: <a href=\"http:\/\/www.flickr.com\/photos\/61779764@N00\/2874803422\/lightbox\/\" target=\"_blank\">Marc-A. G<\/a><\/figcaption><\/figure>\n<\/div>\n<p>Des plans pour couvrir cette cicatrice sont sur la table et je dois avouer, sont plut\u00f4t prometteurs. En partenariat avec le Fond de Solidarit\u00e9 FTQ et Canderel, <a href=\"http:\/\/canderel.altusinsite.com\/fr\/index.php?page=branding_search_buildingdetail&#038;spaceid=721683&#038;suiteid=721701\" target=\"_blank\">le complexe multi-phase de deux b\u00e2timents offrant un total de 1,2 millions de pieds carr\u00e9s serait certifi\u00e9 LEED<\/a>. En plus de couvrir le terrain vague de l&rsquo;ancien Spectrum, une tour de 31 \u00e9tages serait \u00e9rig\u00e9e sur la rue Jeanne-Mance et voil\u00e0 o\u00f9 \u00e7a va brasser.<\/p>\n<div align=\"center\">\n<figure id=\"attachment_1618\" aria-describedby=\"caption-attachment-1618\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/1.jpg\" alt=\"Images: Canderel\" width=\"550\" class=\"size-full wp-image-1618\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/1.jpg 597w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/1-113x150.jpg 113w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/1-226x300.jpg 226w\" sizes=\"(max-width: 597px) 100vw, 597px\" \/><figcaption id=\"caption-attachment-1618\" class=\"wp-caption-text\">Images: Canderel<\/figcaption><\/figure>\n<\/div>\n<p>Le Quartier des Spectacles est un des plus beaux endroits \u00e0 Montr\u00e9al avec ses rues pav\u00e9es, les fontaines de la Place des Festivals et son mobilier design. M\u00eame la Place des Arts et le Complexe Desjardins se sont refait une beaut\u00e9 pour bien s&rsquo;incorporer aux alentours. Il est donc normal que les r\u00e9sidents ce soient appropri\u00e9s l&rsquo;endroit de belle fa\u00e7on. Mais, ce type d&#8217;emplacement attire \u00e9galement ce que les urbanistes appelent des \u00ab\u00a0NIMBYs\u00a0\u00bb ou les \u00ab\u00a0pas dans ma cour\u00a0\u00bb. Un bon exemple, juste au sud du Quartier des Spectacles, sur le Boulevard Ren\u00e9-Levesque au coin de la rue De Bleury est en train de se construire ce qui sera une des belles tours de la ville. Le Marriott Courtyard Centre-Ville de 42 \u00e9tages monte fi\u00e8rement et sa construction, pas encore termin\u00e9, s&rsquo;attire d\u00e9j\u00e0 les critiques, trop grand pour le quartier ou cache la vue (\u00e0 je ne sais pas quoi). Imaginez donc quel bruit fera la construction d&rsquo;une tour, m\u00eame plus petite, directement sur Jeanne-Mance?<\/p>\n<div align=\"center\">\n<figure id=\"attachment_1619\" aria-describedby=\"caption-attachment-1619\" style=\"width: 550px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.mtlurb.com\/forums\/showthread.php\/17846-Marriott-Courtyard-Montr%C3%A9al-Centre-ville?p=165500#post165500\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/Marriott-Courtyard.jpg\" alt=\"Photo: Memphis - MTLUrb.com \" width=\"550\" height=\"821\" class=\"size-full wp-image-1619\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/Marriott-Courtyard.jpg 550w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/Marriott-Courtyard-100x150.jpg 100w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/Marriott-Courtyard-200x300.jpg 200w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a><figcaption id=\"caption-attachment-1619\" class=\"wp-caption-text\">Photo: <a href=\"http:\/\/www.mtlurb.com\/forums\/showthread.php\/17846-Marriott-Courtyard-Montr%C3%A9al-Centre-ville?p=165500#post165500\" target=\"_blank\">Memphis &#8211; MTLUrb.com<\/a><\/figcaption><\/figure>\n<\/div>\n<p>Selon la Commission de la Construction du Qu\u00e9bec, Montr\u00e9al comptait en d\u00e9cembre 2012, 120 chantiers importants en cours, totalisant 14,8 milliards$ dont 29% directement dans Ville-Marie. Cet \u00e9lan est difficile \u00e0 arr\u00eater et attire les investisseurs locaux et internationaux et des tours comme celle que propose Canderel n&rsquo;est qu&rsquo;une autre preuve que la demande est l\u00e0. Il serait d\u00e9solant de voir des investissements 100% priv\u00e9s se faire montrer la porte \u00e0 cause de quelques branleux de pancartes.<\/p>\n<div align=\"center\">\n<figure id=\"attachment_1623\" aria-describedby=\"caption-attachment-1623\" style=\"width: 399px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/ville.montreal.qc.ca\/pls\/portal\/docs\/PAGE\/MTL_STATS_FR\/MEDIA\/DOCUMENTS\/CHANTIERS_D%C9C_2012.PDF\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/charte.jpg\" alt=\"Source: Ville de Montr\u00e9al\" width=\"399\" height=\"500\" class=\"size-full wp-image-1623\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/charte.jpg 399w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/charte-119x150.jpg 119w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/charte-239x300.jpg 239w\" sizes=\"auto, (max-width: 399px) 100vw, 399px\" \/><\/a><figcaption id=\"caption-attachment-1623\" class=\"wp-caption-text\">Source: <a href=\"http:\/\/ville.montreal.qc.ca\/pls\/portal\/docs\/PAGE\/MTL_STATS_FR\/MEDIA\/DOCUMENTS\/CHANTIERS_D%C9C_2012.PDF\" target=\"_blank\">Ville de Montr\u00e9al<\/a><\/figcaption><\/figure>\n<\/div>\n<p>L&rsquo;autre d\u00e9tail o\u00f9 il y aura certainement d\u00e9bat est cette lign\u00e9e de petits commerces de la rue Sainte-Catherine entre les rues Jeanne-Mance et de Bleury. Doit-on construire autour, les d\u00e9truire pour faire place \u00e0 un nouvel endroit public qui s&rsquo;amalgamerait parfaitement avec le quartier, les introduire aux design final du projet Canderel ou simplement leur demander, peut-\u00eatre \u00e0 coup d&rsquo;aide financi\u00e8re, de r\u00e9nover leur fa\u00e7ade qui me font totalement honte. Je ne crois pas que ces b\u00e2tisses aient une valeur patrimoniale et s\u00e9rieusement, je n&rsquo;ai rien contre Ard\u00e8ne ou Eve et Zo\u00e9, mais ce type de boutiques sont-elle vraiment n\u00e9cessaire dans la Place des Festivals?<\/p>\n<p>En conclusion, cette tour est seulement en mode projet et comme trop souvent au Qu\u00e9bec, ce type de proposition de qualit\u00e9 prend \u00e9norm\u00e9ment de temps et de bureaucratie avant de voir le jour en plus d&rsquo;\u00eatre ralenti par une minorit\u00e9 pas tr\u00e8s silencieuse. Esp\u00e9rons seulement que leur date de construction vis\u00e9 pour 2014-2015 sera r\u00e9aliste et que de nouvelle grues apparaitront rapidement dans le ciel de Montr\u00e9al.<\/p>\n<p>Mise \u00e0 jour: 10 avril 2013.<br \/>\nLe <a href=\"http:\/\/tourqds.com\/\" target=\"_blank\">site web officiel<\/a> de cette nouvelle construction est maintenant en ligne. La tour portera le nom de Tour QDS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture approximatif de<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>Un projet de Canderel et du Fond de solidarit\u00e9 FTQ pour couvrir la cicatrice laiss\u00e9 par la d\u00e9molition du Spectrum en 2008 fera des vagues et s&rsquo;attirera les critiques.<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/\">Pour lire l&#039;article&#8230;<span class=\"screen-reader-text\">Tour du Spectrum.<\/span><\/a><\/div>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1,6],"tags":[967,134,30,968,531,966,309],"class_list":["post-1617","post","type-post","status-publish","format-standard","hentry","category-actualite","category-urbanisme","tag-canderel","tag-construction","tag-montreal","tag-place-des-festivals","tag-quartier-des-spectacles","tag-spectrum","tag-tour","excerpt","zoom","full-without-featured","even","excerpt-0"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tour Spectrum<\/title>\n<meta name=\"description\" content=\"Un projet de Canderel et du Fond de solidarit\u00e9 FTQ pour couvrir la cicatrice laiss\u00e9 par la d\u00e9molition du Spectrum en 2008 fera des vagues et s&#039;attirera les critiques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour Spectrum\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/\" \/>\n<meta property=\"og:site_name\" content=\"ProposMontr\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proposmontreal\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/proposmontreal\" \/>\n<meta property=\"article:published_time\" content=\"2013-03-28T15:04:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2013-04-10T11:25:05+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/spectrum.jpg\" \/>\n<meta name=\"author\" content=\"Martin B\u00e9rub\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@proposmontreal\" \/>\n<meta name=\"twitter:site\" content=\"@ProposMontreal\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin B\u00e9rub\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/tour-du-spectrum\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/tour-du-spectrum\\\/\"},\"author\":{\"name\":\"Martin B\u00e9rub\u00e9\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#\\\/schema\\\/person\\\/7d7acef09662dd8c0283a456e39b3254\"},\"headline\":\"Tour du Spectrum.\",\"datePublished\":\"2013-03-28T15:04:36+00:00\",\"dateModified\":\"2013-04-10T11:25:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/tour-du-spectrum\\\/\"},\"wordCount\":665,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/tour-du-spectrum\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/spectrum.jpg\",\"keywords\":[\"Canderel\",\"construction\",\"Montr\u00e9al\",\"place des festivals\",\"Quartier des Spectacles\",\"Spectrum\",\"tour\"],\"articleSection\":[\"Actualit\u00e9\",\"Urbanisme\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/tour-du-spectrum\\\/\",\"url\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/tour-du-spectrum\\\/\",\"name\":\"Tour Spectrum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/tour-du-spectrum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/tour-du-spectrum\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/spectrum.jpg\",\"datePublished\":\"2013-03-28T15:04:36+00:00\",\"dateModified\":\"2013-04-10T11:25:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#\\\/schema\\\/person\\\/7d7acef09662dd8c0283a456e39b3254\"},\"description\":\"Un projet de Canderel et du Fond de solidarit\u00e9 FTQ pour couvrir la cicatrice laiss\u00e9 par la d\u00e9molition du Spectrum en 2008 fera des vagues et s'attirera les critiques.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/tour-du-spectrum\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/tour-du-spectrum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/tour-du-spectrum\\\/#primaryimage\",\"url\":\"http:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/spectrum.jpg\",\"contentUrl\":\"http:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2013\\\/03\\\/spectrum.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/tour-du-spectrum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/proposmontreal.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour du Spectrum.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#website\",\"url\":\"https:\\\/\\\/proposmontreal.com\\\/\",\"name\":\"ProposMontr\u00e9al\",\"description\":\"Histoire, Urbanisme, Architecture et Opinions.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proposmontreal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#\\\/schema\\\/person\\\/7d7acef09662dd8c0283a456e39b3254\",\"name\":\"Martin B\u00e9rub\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g\",\"caption\":\"Martin B\u00e9rub\u00e9\"},\"description\":\"Amoureux de Montr\u00e9al, fascin\u00e9 par l'histoire de la ville, son urbanisme et sa toponymie, ni historien ni sp\u00e9cialiste du sujet, Martin n'\u00e9tait m\u00eame pas n\u00e9 \u00e0 l'\u00e9poque de 99% des sujets discut\u00e9s de ce site. Il aime trouver des r\u00e9ponses aux questions qui sont pos\u00e9es. Les billets que vous lisez ne sont que les r\u00e9sultats de la qu\u00eate vers des r\u00e9ponses et le besoin de partager.\",\"sameAs\":[\"http:\\\/\\\/proposmontreal.com\",\"https:\\\/\\\/www.facebook.com\\\/proposmontreal\",\"https:\\\/\\\/x.com\\\/proposmontreal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tour Spectrum","description":"Un projet de Canderel et du Fond de solidarit\u00e9 FTQ pour couvrir la cicatrice laiss\u00e9 par la d\u00e9molition du Spectrum en 2008 fera des vagues et s'attirera les critiques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour Spectrum","og_url":"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/","og_site_name":"ProposMontr\u00e9al","article_publisher":"https:\/\/www.facebook.com\/proposmontreal","article_author":"https:\/\/www.facebook.com\/proposmontreal","article_published_time":"2013-03-28T15:04:36+00:00","article_modified_time":"2013-04-10T11:25:05+00:00","og_image":[{"url":"http:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/spectrum.jpg","type":"","width":"","height":""}],"author":"Martin B\u00e9rub\u00e9","twitter_card":"summary_large_image","twitter_creator":"@proposmontreal","twitter_site":"@ProposMontreal","twitter_misc":{"\u00c9crit par":"Martin B\u00e9rub\u00e9","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/#article","isPartOf":{"@id":"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/"},"author":{"name":"Martin B\u00e9rub\u00e9","@id":"https:\/\/proposmontreal.com\/#\/schema\/person\/7d7acef09662dd8c0283a456e39b3254"},"headline":"Tour du Spectrum.","datePublished":"2013-03-28T15:04:36+00:00","dateModified":"2013-04-10T11:25:05+00:00","mainEntityOfPage":{"@id":"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/"},"wordCount":665,"commentCount":0,"image":{"@id":"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/#primaryimage"},"thumbnailUrl":"http:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/spectrum.jpg","keywords":["Canderel","construction","Montr\u00e9al","place des festivals","Quartier des Spectacles","Spectrum","tour"],"articleSection":["Actualit\u00e9","Urbanisme"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/","url":"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/","name":"Tour Spectrum","isPartOf":{"@id":"https:\/\/proposmontreal.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/#primaryimage"},"image":{"@id":"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/#primaryimage"},"thumbnailUrl":"http:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/spectrum.jpg","datePublished":"2013-03-28T15:04:36+00:00","dateModified":"2013-04-10T11:25:05+00:00","author":{"@id":"https:\/\/proposmontreal.com\/#\/schema\/person\/7d7acef09662dd8c0283a456e39b3254"},"description":"Un projet de Canderel et du Fond de solidarit\u00e9 FTQ pour couvrir la cicatrice laiss\u00e9 par la d\u00e9molition du Spectrum en 2008 fera des vagues et s'attirera les critiques.","breadcrumb":{"@id":"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/#primaryimage","url":"http:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/spectrum.jpg","contentUrl":"http:\/\/proposmontreal.com\/wp-content\/uploads\/2013\/03\/spectrum.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/proposmontreal.com\/index.php\/tour-du-spectrum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/proposmontreal.com\/"},{"@type":"ListItem","position":2,"name":"Tour du Spectrum."}]},{"@type":"WebSite","@id":"https:\/\/proposmontreal.com\/#website","url":"https:\/\/proposmontreal.com\/","name":"ProposMontr\u00e9al","description":"Histoire, Urbanisme, Architecture et Opinions.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proposmontreal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/proposmontreal.com\/#\/schema\/person\/7d7acef09662dd8c0283a456e39b3254","name":"Martin B\u00e9rub\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g","caption":"Martin B\u00e9rub\u00e9"},"description":"Amoureux de Montr\u00e9al, fascin\u00e9 par l'histoire de la ville, son urbanisme et sa toponymie, ni historien ni sp\u00e9cialiste du sujet, Martin n'\u00e9tait m\u00eame pas n\u00e9 \u00e0 l'\u00e9poque de 99% des sujets discut\u00e9s de ce site. Il aime trouver des r\u00e9ponses aux questions qui sont pos\u00e9es. Les billets que vous lisez ne sont que les r\u00e9sultats de la qu\u00eate vers des r\u00e9ponses et le besoin de partager.","sameAs":["http:\/\/proposmontreal.com","https:\/\/www.facebook.com\/proposmontreal","https:\/\/x.com\/proposmontreal"]}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts\/1617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/comments?post=1617"}],"version-history":[{"count":12,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts\/1617\/revisions"}],"predecessor-version":[{"id":1711,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts\/1617\/revisions\/1711"}],"wp:attachment":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/media?parent=1617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/categories?post=1617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/tags?post=1617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}