{"id":1081,"date":"2012-05-21T17:39:19","date_gmt":"2012-05-21T21:39:19","guid":{"rendered":"http:\/\/proposmontreal.com\/?p=1081"},"modified":"2016-01-01T15:44:44","modified_gmt":"2016-01-01T20:44:44","slug":"la-plage-du-vieux-port","status":"publish","type":"post","link":"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/","title":{"rendered":"La plage du Vieux-Port"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture approximatif de<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p>C\u2019est ind\u00e9niable, le Vieux Port de Montr\u00e9al est s\u00fbrement un des points touristiques le plus visit\u00e9 \u00e0 Montr\u00e9al. Le Quartier des Spectacles, l\u2019Espace pour la vie, le Mont-Royal sont p\u00e2les en comparaison si l\u2019on calcule le nombre d\u2019appareils photo dans le coup per capita. Une journ\u00e9e comme nous avons eu durant ce long week-end avec des 27\u00b0-30\u00b0 celsius et un soleil radieux, le Vieux Port est plein \u00e0 craquer, les Bixis sont partout et dieu merci, les jupes courtes aussi. <\/p>\n<p>Si vous ne le savez pas encore, la Soci\u00e9t\u00e9 du Vieux-Port est en pleine cure de rajeunissement, suite \u00e0 une annonce d\u2019investissement de 190$ millions, nous verrons le r\u00e9am\u00e9nagement du Quai de l\u2019horloge, la remise \u00e0 jour du Hangar #16 et l\u2019am\u00e9nagement du Quai Jacques-Cartiers pr\u00e9vus d\u2019ici le 375e anniversaire de Montr\u00e9al.<\/p>\n<div align=\"center\">\n<iframe loading=\"lazy\" width=\"549\" height=\"309\" src=\"http:\/\/www.youtube.com\/embed\/F2qCqV_00ms?rel=0\" frameborder=\"0\" allowfullscreen><\/iframe>\n<\/div>\n<p>Aujourd&rsquo;hui, je vous parle de l&rsquo;attraction qui ouvrira ces tourniquets tr\u00e8s bient\u00f4t, soit le 16 juin, <a href=\"http:\/\/www.vieuxportdemontreal.com\/activite\/plage-de-l-horloge\" target=\"_blank\">la plage du Quai de l&rsquo;Horloge<\/a> est une installation urbaine d&rsquo;une plage avec sable, espaces de rafra\u00eechissement (douches) des chaises longues et des parasols, mais aucun acc\u00e8s \u00e0 l&rsquo;eau pour y nager ou m\u00eame s&rsquo;y tremper les pieds, la force du courant \u00e9tant trop fort. Un endroit ou se promener en famille les deux pieds dans le sable. Une vue sur la marina et la tour de l&rsquo;horloge datant de 1921. Une promenade d&rsquo;environ 270 m\u00e8tres en bois vous offre une petite marche menant vers la pointe du quai. Certaines personnes reconna\u00eetrons des ressemblances (certains diront un copiez-collez) avec la Sugar Beach de Toronto ce qui n&rsquo;est pas une surprise puisque ces concepteurs, la firme d&rsquo;architecture Montr\u00e9alaise, <a href=\"http:\/\/www.claudecormier.com\/projet\/plage-de-lhorloge\/\" target=\"_blank\">Claude Cormier et Associ\u00e9s<\/a>, sont les m\u00eames qui ont cr\u00e9\u00e9 les deux projets.<\/p>\n<p>Mais un d\u00e9bat commence d\u00e9j\u00e0 sur ce projet qui n&rsquo;est m\u00eame pas encore ouvert. Pour avoir acc\u00e8s \u00e0 cet endroit, vous allez devoir d\u00e9bourser des <a href=\"http:\/\/www.vieuxportdemontreal.com\/activite\/plage-de-l-horloge\" target=\"_blank\">frais d&rsquo;admission<\/a>. Soit 6$par adulte, 5$ pour les personnes de 60 ans et plus, 3$ pour les enfants de 6 \u00e0 12 ans et gratuit pour les enfants de cinq ans et moins. Un prix de famille de 15$ est aussi disponible. Des passes de saisons seront aussi disponible pour 27$ et de 58$ par famille. Ce qui pourra \u00eatre utile pour les r\u00e9sidents du Solano, de l&rsquo;H\u00e9ritage ou des autres condos du coin. Aussi, pour ceux qui travail dans le coin et voudrait prendre un peu de soleil durant leur heure de d\u00eener. Le d\u00e9bat est sur le fait qu&rsquo;ils ont pris un endroit public gratuit et qu&rsquo;ils l&rsquo;ont maintenant \u00ab\u00a0privatis\u00e9\u00a0\u00bb en le rendant payant.<\/p>\n<div align=\"center\">\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_hor_01.jpg\" alt=\"Plage Vieux Port\" title=\"Plage Vieux Port\" width=\"550\" height=\"293\" class=\"alignnone size-full wp-image-1082\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_hor_01.jpg 550w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_hor_01-150x79.jpg 150w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_hor_01-300x159.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/>\n<\/div>\n<p>Certain vous diront que la plage ayant co\u00fbt\u00e9 4$ millions a \u00e9t\u00e9 pay\u00e9 \u00e0 m\u00eame nos taxes et qu&rsquo;automatiquement, elle devrait \u00eatre gratuite. \u00c0 mon avis, je suis pour le concept d&rsquo;utilisateur-payeur, ce qui me semble ad\u00e9quat dans ce contexte. Le Vieux-Montr\u00e9al est utilis\u00e9 par 99,9% des touristes (pas un chiffre officiel) et ces m\u00eames touristes d\u00e9bourseront avec plaisir le 6$ pour entrer sur la plage, avec des temp\u00e9ratures oscillant autour du 30\u00b0, cet endroit sera toujours plein&#8230; de touriste.<\/p>\n<p>Ensuite il y a la bouffe, par exemple, le restaurant La Sc\u00e8na sur le quai Jacques-Cartier est sous contrat avec le r\u00e9put\u00e9 traiteur Agnus De\u00ef. Le restaurant de la plage, lui, sera sous la toque du chef Giovanni Appolo, vedette de la cuisine Montr\u00e9alaise. Le soir, \u00e0 la pointe du quai, les noctambules pourront se r\u00e9unir pour boire, manger et bavarder entre amis en regardant la nuit tomb\u00e9e sur le fleuve et en b\u00e9n\u00e9ficiant d&rsquo;un site exceptionnel pour admirer les feux d&rsquo;artifices. Je n&rsquo;ai pas \u00e9t\u00e9 dans la possibilit\u00e9 de trouver cette information, mais j&rsquo;ai l&rsquo;impression qu&rsquo;apporter sa glaci\u00e8re avec de la boisson sera interdite, il faudra donc profiter de ce qu&rsquo;il y a sur place. Fait \u00e0 noter qu&rsquo;un des commanditaire majeur est l&rsquo;eau Eska, vous pouvez donc vous attendre \u00e0 trouver de l&rsquo;eau en bouteille \u00e0 2$-3$. Les autres commanditaires sont les Vins de Provence, Sleeman, Coca-Cola et Coppertone, il sera donc possible de pouvoir prendre un verre sur place. Personnellement, \u00e9tant dans le domaine de l&rsquo;\u00e9v\u00e9nementiel \u00e0 Montr\u00e9al, je me demande s&rsquo;il sera possible de r\u00e9server la plage enti\u00e8re pour un \u00ab\u00a0beach party\u00a0\u00bb de compagnie ou pour un espace mariage?<\/p>\n<div align=\"center\">\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_vert_02.jpg\" alt=\"Plage Vieux-Port Montr\u00e9al\" title=\"Plage Vieux-Port Montr\u00e9al\" width=\"550\" height=\"353\" class=\"alignnone size-full wp-image-1084\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_vert_02.jpg 550w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_vert_02-150x96.jpg 150w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_vert_02-300x192.jpg 300w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/>\n<\/div>\n<p>En conclusion, est-ce que la plage deviendra un endroit aussi branch\u00e9 que les Terrasses Bonsecour? Sera-t-elle un \u00e9chec commercial ou un succ\u00e8s sur toute la ligne?Une chose est certaine, c&rsquo;est que pour 6$, c&rsquo;est moins que la plupart des \u00ab\u00a0cover-charge\u00a0\u00bb que je me fais charger dans certain bars de la ville. Je peux vous garantir que vous allez m&rsquo;y retrouver \u00e0 quelques reprises et la passe saisonni\u00e8re \u00e0 27$ me semble un bon prix. Je dois avouer que j&rsquo;aimerais mieux l&rsquo;avoir gratuite, mais l&rsquo;endroit est relativement petit et une plage en ville, surtout avec nos belles Montr\u00e9alaises, sera le bienvenu et populaire.<\/p>\n<p>Et vous, irez-vous sur la plage du Vieux-Port ?<\/p>\n<div align=\"center\">\n<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_vert.jpg\" alt=\"Plage vieux-Port\" title=\"Plage vieux-Port\" width=\"367\" height=\"550\" class=\"alignnone size-full wp-image-1083\" srcset=\"https:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_vert.jpg 367w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_vert-100x150.jpg 100w, https:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_vert-200x300.jpg 200w\" sizes=\"auto, (max-width: 367px) 100vw, 367px\" \/>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture approximatif de<\/span> <span class=\"rt-time\"> 3<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>C\u2019est ind\u00e9niable, le Vieux Port de Montr\u00e9al est s\u00fbrement un des points touristiques le plus visit\u00e9 \u00e0 Montr\u00e9al. Le Quartier des Spectacles, l\u2019Espace pour la vie, le Mont-Royal sont p\u00e2les en comparaison si l\u2019on calcule le nombre d\u2019appareils photo dans le coup per capita. Une journ\u00e9e comme nous avons eu durant ce long week-end avec des 27\u00b0-30\u00b0 celsius et un soleil radieux, le Vieux Port est plein \u00e0 craquer, les Bixis sont partout et dieu merci, les jupes courtes aussi. <\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/\">Pour lire l&#039;article&#8230;<span class=\"screen-reader-text\">La plage du Vieux-Port<\/span><\/a><\/div>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1,6],"tags":[751,749,30,750,747,653,748,746],"class_list":["post-1081","post","type-post","status-publish","format-standard","hentry","category-actualite","category-urbanisme","tag-appollo","tag-eska","tag-montreal","tag-parasol","tag-plage","tag-sleeman","tag-urbaine","tag-vieux-port","excerpt","zoom","full-without-featured","even","excerpt-0"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La plage du Vieux-Port<\/title>\n<meta name=\"description\" content=\"C\u2019est ind\u00e9niable, le Vieux Port de Montr\u00e9al est s\u00fbrement un des points touristiques le plus visit\u00e9 \u00e0 Montr\u00e9al. Le Quartier des Spectacles, l\u2019Espace pour la vie, le Mont-Royal sont p\u00e2les en comparaison si l\u2019on calcule le nombre d\u2019appareils photo dans le coup per capita. Une journ\u00e9e comme nous avons eu durant ce long week-end avec des 27\u00b0-30\u00b0 celsius et un soleil radieux, le Vieux Port est plein \u00e0 craquer, les Bixis sont partout et dieu merci, les jupes courtes aussi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La plage du Vieux-Port\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/\" \/>\n<meta property=\"og:site_name\" content=\"ProposMontr\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proposmontreal\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/proposmontreal\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-21T21:39:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-01T20:44:44+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_hor_01.jpg\" \/>\n<meta name=\"author\" content=\"Martin B\u00e9rub\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@proposmontreal\" \/>\n<meta name=\"twitter:site\" content=\"@ProposMontreal\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin B\u00e9rub\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/la-plage-du-vieux-port\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/la-plage-du-vieux-port\\\/\"},\"author\":{\"name\":\"Martin B\u00e9rub\u00e9\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#\\\/schema\\\/person\\\/7d7acef09662dd8c0283a456e39b3254\"},\"headline\":\"La plage du Vieux-Port\",\"datePublished\":\"2012-05-21T21:39:19+00:00\",\"dateModified\":\"2016-01-01T20:44:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/la-plage-du-vieux-port\\\/\"},\"wordCount\":834,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/la-plage-du-vieux-port\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/plage_hor_01.jpg\",\"keywords\":[\"Appollo\",\"Eska\",\"Montr\u00e9al\",\"parasol\",\"Plage\",\"sleeman\",\"urbaine\",\"vieux-port\"],\"articleSection\":[\"Actualit\u00e9\",\"Urbanisme\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/la-plage-du-vieux-port\\\/\",\"url\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/la-plage-du-vieux-port\\\/\",\"name\":\"La plage du Vieux-Port\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/la-plage-du-vieux-port\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/la-plage-du-vieux-port\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/plage_hor_01.jpg\",\"datePublished\":\"2012-05-21T21:39:19+00:00\",\"dateModified\":\"2016-01-01T20:44:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#\\\/schema\\\/person\\\/7d7acef09662dd8c0283a456e39b3254\"},\"description\":\"C\u2019est ind\u00e9niable, le Vieux Port de Montr\u00e9al est s\u00fbrement un des points touristiques le plus visit\u00e9 \u00e0 Montr\u00e9al. Le Quartier des Spectacles, l\u2019Espace pour la vie, le Mont-Royal sont p\u00e2les en comparaison si l\u2019on calcule le nombre d\u2019appareils photo dans le coup per capita. Une journ\u00e9e comme nous avons eu durant ce long week-end avec des 27\u00b0-30\u00b0 celsius et un soleil radieux, le Vieux Port est plein \u00e0 craquer, les Bixis sont partout et dieu merci, les jupes courtes aussi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/la-plage-du-vieux-port\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/la-plage-du-vieux-port\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/la-plage-du-vieux-port\\\/#primaryimage\",\"url\":\"http:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/plage_hor_01.jpg\",\"contentUrl\":\"http:\\\/\\\/proposmontreal.com\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/plage_hor_01.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/la-plage-du-vieux-port\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/proposmontreal.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La plage du Vieux-Port\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#website\",\"url\":\"https:\\\/\\\/proposmontreal.com\\\/\",\"name\":\"ProposMontr\u00e9al\",\"description\":\"Histoire, Urbanisme, Architecture et Opinions.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proposmontreal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#\\\/schema\\\/person\\\/7d7acef09662dd8c0283a456e39b3254\",\"name\":\"Martin B\u00e9rub\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g\",\"caption\":\"Martin B\u00e9rub\u00e9\"},\"description\":\"Amoureux de Montr\u00e9al, fascin\u00e9 par l'histoire de la ville, son urbanisme et sa toponymie, ni historien ni sp\u00e9cialiste du sujet, Martin n'\u00e9tait m\u00eame pas n\u00e9 \u00e0 l'\u00e9poque de 99% des sujets discut\u00e9s de ce site. Il aime trouver des r\u00e9ponses aux questions qui sont pos\u00e9es. Les billets que vous lisez ne sont que les r\u00e9sultats de la qu\u00eate vers des r\u00e9ponses et le besoin de partager.\",\"sameAs\":[\"http:\\\/\\\/proposmontreal.com\",\"https:\\\/\\\/www.facebook.com\\\/proposmontreal\",\"https:\\\/\\\/x.com\\\/proposmontreal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La plage du Vieux-Port","description":"C\u2019est ind\u00e9niable, le Vieux Port de Montr\u00e9al est s\u00fbrement un des points touristiques le plus visit\u00e9 \u00e0 Montr\u00e9al. Le Quartier des Spectacles, l\u2019Espace pour la vie, le Mont-Royal sont p\u00e2les en comparaison si l\u2019on calcule le nombre d\u2019appareils photo dans le coup per capita. Une journ\u00e9e comme nous avons eu durant ce long week-end avec des 27\u00b0-30\u00b0 celsius et un soleil radieux, le Vieux Port est plein \u00e0 craquer, les Bixis sont partout et dieu merci, les jupes courtes aussi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/","og_locale":"fr_FR","og_type":"article","og_title":"La plage du Vieux-Port","og_url":"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/","og_site_name":"ProposMontr\u00e9al","article_publisher":"https:\/\/www.facebook.com\/proposmontreal","article_author":"https:\/\/www.facebook.com\/proposmontreal","article_published_time":"2012-05-21T21:39:19+00:00","article_modified_time":"2016-01-01T20:44:44+00:00","og_image":[{"url":"http:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_hor_01.jpg","type":"","width":"","height":""}],"author":"Martin B\u00e9rub\u00e9","twitter_card":"summary_large_image","twitter_creator":"@proposmontreal","twitter_site":"@ProposMontreal","twitter_misc":{"\u00c9crit par":"Martin B\u00e9rub\u00e9","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/#article","isPartOf":{"@id":"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/"},"author":{"name":"Martin B\u00e9rub\u00e9","@id":"https:\/\/proposmontreal.com\/#\/schema\/person\/7d7acef09662dd8c0283a456e39b3254"},"headline":"La plage du Vieux-Port","datePublished":"2012-05-21T21:39:19+00:00","dateModified":"2016-01-01T20:44:44+00:00","mainEntityOfPage":{"@id":"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/"},"wordCount":834,"commentCount":0,"image":{"@id":"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/#primaryimage"},"thumbnailUrl":"http:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_hor_01.jpg","keywords":["Appollo","Eska","Montr\u00e9al","parasol","Plage","sleeman","urbaine","vieux-port"],"articleSection":["Actualit\u00e9","Urbanisme"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/","url":"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/","name":"La plage du Vieux-Port","isPartOf":{"@id":"https:\/\/proposmontreal.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/#primaryimage"},"image":{"@id":"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/#primaryimage"},"thumbnailUrl":"http:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_hor_01.jpg","datePublished":"2012-05-21T21:39:19+00:00","dateModified":"2016-01-01T20:44:44+00:00","author":{"@id":"https:\/\/proposmontreal.com\/#\/schema\/person\/7d7acef09662dd8c0283a456e39b3254"},"description":"C\u2019est ind\u00e9niable, le Vieux Port de Montr\u00e9al est s\u00fbrement un des points touristiques le plus visit\u00e9 \u00e0 Montr\u00e9al. Le Quartier des Spectacles, l\u2019Espace pour la vie, le Mont-Royal sont p\u00e2les en comparaison si l\u2019on calcule le nombre d\u2019appareils photo dans le coup per capita. Une journ\u00e9e comme nous avons eu durant ce long week-end avec des 27\u00b0-30\u00b0 celsius et un soleil radieux, le Vieux Port est plein \u00e0 craquer, les Bixis sont partout et dieu merci, les jupes courtes aussi.","breadcrumb":{"@id":"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/#primaryimage","url":"http:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_hor_01.jpg","contentUrl":"http:\/\/proposmontreal.com\/wp-content\/uploads\/2012\/05\/plage_hor_01.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/proposmontreal.com\/index.php\/la-plage-du-vieux-port\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/proposmontreal.com\/"},{"@type":"ListItem","position":2,"name":"La plage du Vieux-Port"}]},{"@type":"WebSite","@id":"https:\/\/proposmontreal.com\/#website","url":"https:\/\/proposmontreal.com\/","name":"ProposMontr\u00e9al","description":"Histoire, Urbanisme, Architecture et Opinions.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proposmontreal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/proposmontreal.com\/#\/schema\/person\/7d7acef09662dd8c0283a456e39b3254","name":"Martin B\u00e9rub\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g","caption":"Martin B\u00e9rub\u00e9"},"description":"Amoureux de Montr\u00e9al, fascin\u00e9 par l'histoire de la ville, son urbanisme et sa toponymie, ni historien ni sp\u00e9cialiste du sujet, Martin n'\u00e9tait m\u00eame pas n\u00e9 \u00e0 l'\u00e9poque de 99% des sujets discut\u00e9s de ce site. Il aime trouver des r\u00e9ponses aux questions qui sont pos\u00e9es. Les billets que vous lisez ne sont que les r\u00e9sultats de la qu\u00eate vers des r\u00e9ponses et le besoin de partager.","sameAs":["http:\/\/proposmontreal.com","https:\/\/www.facebook.com\/proposmontreal","https:\/\/x.com\/proposmontreal"]}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts\/1081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/comments?post=1081"}],"version-history":[{"count":7,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts\/1081\/revisions"}],"predecessor-version":[{"id":3996,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts\/1081\/revisions\/3996"}],"wp:attachment":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/media?parent=1081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/categories?post=1081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/tags?post=1081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}