{"id":1038,"date":"2012-04-07T15:49:13","date_gmt":"2012-04-07T19:49:13","guid":{"rendered":"http:\/\/proposmontreal.com\/?p=1038"},"modified":"2012-04-07T15:49:13","modified_gmt":"2012-04-07T19:49:13","slug":"finalement-demolition-sur-st-laurent","status":"publish","type":"post","link":"https:\/\/proposmontreal.com\/index.php\/finalement-demolition-sur-st-laurent\/","title":{"rendered":"Finalement, d\u00e9molition sur St-laurent"},"content":{"rendered":"<span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture approximatif de<\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span><p>De temps en temps, j&rsquo;ai l&rsquo;impression que je radote, je ne cesse de r\u00e9p\u00e9ter que trop de gens vivent dans le pass\u00e9. Quand le Spectrum a \u00e9t\u00e9 mis \u00e0 terre, trop de gens voyaient dans ce b\u00e2timent sans valeur patrimoniale quelque chose qui devait \u00eatre sauv\u00e9. M\u00eame histoire pour le Medley et pourtant, je tiens \u00e0 rappeler que les souvenirs sont souvent plus important que la pierre et les briques. Comme j&rsquo;\u00e9crivais voil\u00e0 pas si longtemps, la premi\u00e8re joute de hockey a \u00e9t\u00e9 jou\u00e9 \u00e0 un endroit qui est devenu aujourd&rsquo;hui un stationnement \u00e9tag\u00e9.<\/p>\n<p>Ce billet se veut une r\u00e9ponse \u00e0 Madame Phyllis Lambert et Monsieur Dinu Bumbaru, dont je respecte l&rsquo;opinion, font encore la preuve dans <a href=\"http:\/\/www.ledevoir.com\/societe\/actualites-en-societe\/346969\/revitalisation-du-patrimoine-sauvons-le-boulevard-saint-laurent\" target=\"_blank\">Le Devoir d&rsquo;aujourd&rsquo;hui<\/a> que trop de gens habitent encore le pass\u00e9. Cette fois-ci leur pancartes de contestations s&rsquo;arr\u00eatent sur l&rsquo;\u00eelot du Monument National. Finalement, cette enfilade de b\u00e2timents oubli\u00e9s et d\u00e9labr\u00e9s auront la visite des pelles des d\u00e9molisseurs \u00e0 partir du 9 avril. Situ\u00e9 entre deux extr\u00eame, soit le merveilleux Monument National et de l&rsquo;autre c\u00f4t\u00e9 du spectre de qualit\u00e9&#8230; Le Caf\u00e9 Cl\u00e9opatre. Ces \u00e9difices qui <a href=\"http:\/\/www.le2-22.com\/?p=315\" target=\"_blank\">ont d\u00e9j\u00e0 eu une valeur patrimoniale<\/a> ont \u00e9t\u00e9 laiss\u00e9s \u00e0 la merci des \u00e9l\u00e9ments depuis longtemps et maintenant m\u00e9ritent de partir vers un monde meilleur. Vous savez, l&rsquo;euthanasie et la mort dans la dignit\u00e9 n&rsquo;est pas r\u00e9serv\u00e9e qu&rsquo;aux humains.<\/p>\n<p>Les 20 ans entre 1980 et 2000 ont offert \u00e0 la ville un d\u00e9clin qui ne commence qu&rsquo;\u00e0 \u00eatre corrig\u00e9. Les ann\u00e9es noires sont derri\u00e8res nous et je crois fortement que Montr\u00e9al a besoin d&rsquo;\u00eatre une ville du future et non du pass\u00e9. Personne ne va au sud de St-Laurent pour visiter le pass\u00e9, ils y vont pour voir ce qu&rsquo;est un centre-ville habit\u00e9 et en plein effervescence et ce que je vois depuis trop longtemps, c&rsquo;est une rue qui a besoin d&rsquo;un peu plus qu&rsquo;un simple lifting. Le Boulevard St-Laurent n&rsquo;est pas \u00e0 Montr\u00e9al ce que la Tour Eifel est \u00e0 Paris, absolument personne vient ici pour voir ce coin de rue.<\/p>\n<p>Je ne d\u00e9nigrerais pas leurs arguments, la \u00ab\u00a0Main\u00a0\u00bb et ces \u00e9difices mentionn\u00e9s ont d\u00e9j\u00e0 \u00e9t\u00e9 le centre n\u00e9vralgique de Montr\u00e9al, la division entre l&rsquo;Est et l&rsquo;Ouest, le \u00ab\u00a0red light\u00a0\u00bb et autre surnom que l&rsquo;on peut donner \u00e0 l&rsquo;endroit, mais, en 2012, ne serait-ce t&rsquo;il pas le bon moment, pendant que Montr\u00e9al est dans une belle remont\u00e9e de retaper ce coin de rue mythique. Le Quartier des Spectacles est en train de transformer la rue Ste-Catherine entre Bleury et St-Laurent en un endroit moderne qui pourra faire au cours des d\u00e9cennies \u00e0 venir un nouveau centre de l&rsquo;activit\u00e9 de la ville.<\/p>\n<p>Je suis fatigu\u00e9 de voir ces branleux de pancartes qui sont accroch\u00e9s \u00e0 ce que Montr\u00e9al a d\u00e9j\u00e0 \u00e9t\u00e9 et qui nous emp\u00eache d&rsquo;aller de l&rsquo;avant. Nous ne sommes plus la m\u00e9tropole du canada, Toronto a gagn\u00e9 cette bataille, Vancouver et Calgary ne sont pas loin derri\u00e8re nous. Avant de se faire rattraper, donnons \u00e0 Montr\u00e9al ce qu&rsquo;il m\u00e9rite depuis trop longtemps, un centre-ville o\u00f9 il est possible de perdre son temps. Il est temps de regarder en avant, car le pass\u00e9, ne vaut pas toujours la peine \u00e0 sauvegarder.<\/p>\n<p>Nous ne renions pas le pass\u00e9, nous ne faisons qu&rsquo;am\u00e9liorer notre futur.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><span class=\"span-reading-time rt-reading-time\" style=\"display: block;\"><span class=\"rt-label rt-prefix\">Temps de lecture approximatif de<\/span> <span class=\"rt-time\"> 2<\/span> <span class=\"rt-label rt-postfix\">minutes<\/span><\/span>Finalement, cette enfilade de b\u00e2timents oubli\u00e9s et d\u00e9labr\u00e9s auront la visite des pelles des d\u00e9molisseurs \u00e0 partir du 9 avril. Situ\u00e9 entre deux extr\u00eame, soit le merveilleux Monument National et de l&rsquo;autre c\u00f4t\u00e9 du spectre de qualit\u00e9&#8230; Le Caf\u00e9 Cl\u00e9opatre.<\/p>\n<div class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/proposmontreal.com\/index.php\/finalement-demolition-sur-st-laurent\/\">Pour lire l&#039;article&#8230;<span class=\"screen-reader-text\">Finalement, d\u00e9molition sur St-laurent<\/span><\/a><\/div>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1,3,393,6],"tags":[625,12,711,712,709,674,30,710,531,708,676],"class_list":["post-1038","post","type-post","status-publish","format-standard","hentry","category-actualite","category-culture","category-histoire-2","category-urbanisme","tag-2-22","tag-bumbaru","tag-cafe-cleopatre","tag-club-soda","tag-demolition","tag-main","tag-montreal","tag-monument-national","tag-quartier-des-spectacles","tag-red-light","tag-st-laurent","excerpt","zoom","full-without-featured","even","excerpt-0"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Finalement, d\u00e9molition sur St-laurent<\/title>\n<meta name=\"description\" content=\"Finalement, cette enfilade de b\u00e2timents oubli\u00e9s et d\u00e9labr\u00e9s auront la visite des pelles des d\u00e9molisseurs \u00e0 partir du 9 avril. Situ\u00e9 entre deux extr\u00eame, soit le merveilleux Monument National et de l&#039;autre c\u00f4t\u00e9 du spectre de qualit\u00e9... Le Caf\u00e9 Cl\u00e9opatre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/proposmontreal.com\/index.php\/finalement-demolition-sur-st-laurent\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finalement, d\u00e9molition sur St-laurent\" \/>\n<meta property=\"og:url\" content=\"https:\/\/proposmontreal.com\/index.php\/finalement-demolition-sur-st-laurent\/\" \/>\n<meta property=\"og:site_name\" content=\"ProposMontr\u00e9al\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/proposmontreal\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/proposmontreal\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-07T19:49:13+00:00\" \/>\n<meta name=\"author\" content=\"Martin B\u00e9rub\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@proposmontreal\" \/>\n<meta name=\"twitter:site\" content=\"@ProposMontreal\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Martin B\u00e9rub\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/finalement-demolition-sur-st-laurent\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/finalement-demolition-sur-st-laurent\\\/\"},\"author\":{\"name\":\"Martin B\u00e9rub\u00e9\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#\\\/schema\\\/person\\\/7d7acef09662dd8c0283a456e39b3254\"},\"headline\":\"Finalement, d\u00e9molition sur St-laurent\",\"datePublished\":\"2012-04-07T19:49:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/finalement-demolition-sur-st-laurent\\\/\"},\"wordCount\":569,\"commentCount\":1,\"keywords\":[\"2-22\",\"Bumbaru\",\"Caf\u00e9 Cl\u00e9opatre\",\"Club Soda\",\"D\u00e9molition\",\"main\",\"Montr\u00e9al\",\"Monument national\",\"Quartier des Spectacles\",\"red-Light\",\"st-Laurent\"],\"articleSection\":[\"Actualit\u00e9\",\"Culture\",\"Histoire\",\"Urbanisme\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/finalement-demolition-sur-st-laurent\\\/\",\"url\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/finalement-demolition-sur-st-laurent\\\/\",\"name\":\"Finalement, d\u00e9molition sur St-laurent\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#website\"},\"datePublished\":\"2012-04-07T19:49:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#\\\/schema\\\/person\\\/7d7acef09662dd8c0283a456e39b3254\"},\"description\":\"Finalement, cette enfilade de b\u00e2timents oubli\u00e9s et d\u00e9labr\u00e9s auront la visite des pelles des d\u00e9molisseurs \u00e0 partir du 9 avril. Situ\u00e9 entre deux extr\u00eame, soit le merveilleux Monument National et de l'autre c\u00f4t\u00e9 du spectre de qualit\u00e9... Le Caf\u00e9 Cl\u00e9opatre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/finalement-demolition-sur-st-laurent\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/finalement-demolition-sur-st-laurent\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/index.php\\\/finalement-demolition-sur-st-laurent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/proposmontreal.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finalement, d\u00e9molition sur St-laurent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#website\",\"url\":\"https:\\\/\\\/proposmontreal.com\\\/\",\"name\":\"ProposMontr\u00e9al\",\"description\":\"Histoire, Urbanisme, Architecture et Opinions.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/proposmontreal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/proposmontreal.com\\\/#\\\/schema\\\/person\\\/7d7acef09662dd8c0283a456e39b3254\",\"name\":\"Martin B\u00e9rub\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g\",\"caption\":\"Martin B\u00e9rub\u00e9\"},\"description\":\"Amoureux de Montr\u00e9al, fascin\u00e9 par l'histoire de la ville, son urbanisme et sa toponymie, ni historien ni sp\u00e9cialiste du sujet, Martin n'\u00e9tait m\u00eame pas n\u00e9 \u00e0 l'\u00e9poque de 99% des sujets discut\u00e9s de ce site. Il aime trouver des r\u00e9ponses aux questions qui sont pos\u00e9es. Les billets que vous lisez ne sont que les r\u00e9sultats de la qu\u00eate vers des r\u00e9ponses et le besoin de partager.\",\"sameAs\":[\"http:\\\/\\\/proposmontreal.com\",\"https:\\\/\\\/www.facebook.com\\\/proposmontreal\",\"https:\\\/\\\/x.com\\\/proposmontreal\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finalement, d\u00e9molition sur St-laurent","description":"Finalement, cette enfilade de b\u00e2timents oubli\u00e9s et d\u00e9labr\u00e9s auront la visite des pelles des d\u00e9molisseurs \u00e0 partir du 9 avril. Situ\u00e9 entre deux extr\u00eame, soit le merveilleux Monument National et de l'autre c\u00f4t\u00e9 du spectre de qualit\u00e9... Le Caf\u00e9 Cl\u00e9opatre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/proposmontreal.com\/index.php\/finalement-demolition-sur-st-laurent\/","og_locale":"fr_FR","og_type":"article","og_title":"Finalement, d\u00e9molition sur St-laurent","og_url":"https:\/\/proposmontreal.com\/index.php\/finalement-demolition-sur-st-laurent\/","og_site_name":"ProposMontr\u00e9al","article_publisher":"https:\/\/www.facebook.com\/proposmontreal","article_author":"https:\/\/www.facebook.com\/proposmontreal","article_published_time":"2012-04-07T19:49:13+00:00","author":"Martin B\u00e9rub\u00e9","twitter_card":"summary_large_image","twitter_creator":"@proposmontreal","twitter_site":"@ProposMontreal","twitter_misc":{"\u00c9crit par":"Martin B\u00e9rub\u00e9","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/proposmontreal.com\/index.php\/finalement-demolition-sur-st-laurent\/#article","isPartOf":{"@id":"https:\/\/proposmontreal.com\/index.php\/finalement-demolition-sur-st-laurent\/"},"author":{"name":"Martin B\u00e9rub\u00e9","@id":"https:\/\/proposmontreal.com\/#\/schema\/person\/7d7acef09662dd8c0283a456e39b3254"},"headline":"Finalement, d\u00e9molition sur St-laurent","datePublished":"2012-04-07T19:49:13+00:00","mainEntityOfPage":{"@id":"https:\/\/proposmontreal.com\/index.php\/finalement-demolition-sur-st-laurent\/"},"wordCount":569,"commentCount":1,"keywords":["2-22","Bumbaru","Caf\u00e9 Cl\u00e9opatre","Club Soda","D\u00e9molition","main","Montr\u00e9al","Monument national","Quartier des Spectacles","red-Light","st-Laurent"],"articleSection":["Actualit\u00e9","Culture","Histoire","Urbanisme"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/proposmontreal.com\/index.php\/finalement-demolition-sur-st-laurent\/","url":"https:\/\/proposmontreal.com\/index.php\/finalement-demolition-sur-st-laurent\/","name":"Finalement, d\u00e9molition sur St-laurent","isPartOf":{"@id":"https:\/\/proposmontreal.com\/#website"},"datePublished":"2012-04-07T19:49:13+00:00","author":{"@id":"https:\/\/proposmontreal.com\/#\/schema\/person\/7d7acef09662dd8c0283a456e39b3254"},"description":"Finalement, cette enfilade de b\u00e2timents oubli\u00e9s et d\u00e9labr\u00e9s auront la visite des pelles des d\u00e9molisseurs \u00e0 partir du 9 avril. Situ\u00e9 entre deux extr\u00eame, soit le merveilleux Monument National et de l'autre c\u00f4t\u00e9 du spectre de qualit\u00e9... Le Caf\u00e9 Cl\u00e9opatre.","breadcrumb":{"@id":"https:\/\/proposmontreal.com\/index.php\/finalement-demolition-sur-st-laurent\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/proposmontreal.com\/index.php\/finalement-demolition-sur-st-laurent\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/proposmontreal.com\/index.php\/finalement-demolition-sur-st-laurent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/proposmontreal.com\/"},{"@type":"ListItem","position":2,"name":"Finalement, d\u00e9molition sur St-laurent"}]},{"@type":"WebSite","@id":"https:\/\/proposmontreal.com\/#website","url":"https:\/\/proposmontreal.com\/","name":"ProposMontr\u00e9al","description":"Histoire, Urbanisme, Architecture et Opinions.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/proposmontreal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/proposmontreal.com\/#\/schema\/person\/7d7acef09662dd8c0283a456e39b3254","name":"Martin B\u00e9rub\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c584d9147b7b50bb9ff2edf1db3d93d38f22473bdde645a7942ee41f752cce3f?s=96&d=blank&r=g","caption":"Martin B\u00e9rub\u00e9"},"description":"Amoureux de Montr\u00e9al, fascin\u00e9 par l'histoire de la ville, son urbanisme et sa toponymie, ni historien ni sp\u00e9cialiste du sujet, Martin n'\u00e9tait m\u00eame pas n\u00e9 \u00e0 l'\u00e9poque de 99% des sujets discut\u00e9s de ce site. Il aime trouver des r\u00e9ponses aux questions qui sont pos\u00e9es. Les billets que vous lisez ne sont que les r\u00e9sultats de la qu\u00eate vers des r\u00e9ponses et le besoin de partager.","sameAs":["http:\/\/proposmontreal.com","https:\/\/www.facebook.com\/proposmontreal","https:\/\/x.com\/proposmontreal"]}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts\/1038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/comments?post=1038"}],"version-history":[{"count":2,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts\/1038\/revisions"}],"predecessor-version":[{"id":1040,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/posts\/1038\/revisions\/1040"}],"wp:attachment":[{"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/media?parent=1038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/categories?post=1038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/proposmontreal.com\/index.php\/wp-json\/wp\/v2\/tags?post=1038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}